{"id":187187,"date":"2017-09-28T11:55:37","date_gmt":"2017-09-28T15:55:37","guid":{"rendered":"http:\/\/desarrollo.ip.gov.py\/ip\/?p=187187"},"modified":"2017-09-28T11:55:37","modified_gmt":"2017-09-28T15:55:37","slug":"docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/","title":{"rendered":"Docentes del sector privado- subvencionado pueden postularse para becas a Colombia"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Asunci\u00f3n, IP.-<\/strong> <\/em>El programa de becas \u00abCarlos Antonio L\u00f3pez\u00bb (Becal)\u00a0ampli\u00f3 el periodo de postulaci\u00f3n para Colombia, dirigido originalmente a docentes del sector oficial, extendiendo la oportunidad a docentes del sector privado- subvencionado.\u00a0<!--more--><\/p>\n<p style=\"text-align: justify;\">El coordinador de Becal, Federico Mora, anunci\u00f3 que el plazo se extiende hasta el pr\u00f3ximo 6 de octubre, debido a que no se lleg\u00f3 a la cantidad de postulantes esperada. Indic\u00f3 que la convocatoria estaba originalmente destinada a maestros del sector oficial, y que se decidi\u00f3 tambi\u00e9n abrirla para educadores del sector privado- subvencionado.<\/p>\n<p style=\"text-align: justify;\">\u201cInvitamos a todos los docentes del sector privado subvencionado a considerar la convocatoria y a tomar la oportunidad de realizar estudios de especializaci\u00f3n en el exterior en tres \u00e1reas muy concretas que son Matem\u00e1ticas, Ciencias y Lengua y Literatura. Adem\u00e1s, a nivel de directores para la formaci\u00f3n en gesti\u00f3n de la educaci\u00f3n\u201d, dijo.<\/p>\n<p style=\"text-align: justify;\">En la conferencia de prensa tambi\u00e9n se inform\u00f3 que en menos de dos meses de su lanzamiento, el producto financiera proporcionado por\u00a0el Banco Nacional de Fomento (BNF) para profesionales que ya se encuentran cursando sus maestr\u00edas y doctorados en universidades del exterior otorg\u00f3 m\u00e1s de 2.000 millones de guaran\u00edes en cr\u00e9ditos.<\/p>\n<p style=\"text-align: justify;\">Este producto forma parte de un acompa\u00f1amiento que brinda el programa Becal a los profesionales que apuntan a especializarse en el exterior.<\/p>\n<figure id=\"attachment_187168\" aria-describedby=\"caption-attachment-187168\" style=\"width: 323px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-187168\" src=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-representante--600x380.jpg\" alt=\"\" width=\"323\" height=\"204\" srcset=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-representante--600x380.jpg 600w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-representante--768x487.jpg 768w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-representante--696x441.jpg 696w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-representante--662x420.jpg 662w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-representante-.jpg 1000w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><figcaption id=\"caption-attachment-187168\" class=\"wp-caption-text\">Juan Gustale, del Banco Nacional de Fomento. Foto IP Paraguay<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">De acuerdo a lo informado por el representante del Banco Nacional de Fomento, Juan Gustale, son 15 los profesionales que fueron beneficiados con los pr\u00e9stamos hasta la fecha, quienes actualmente ya se encuentran cursando sus estudios en el extranjero.<\/p>\n<p style=\"text-align: justify;\">\u201cLos resultados nos da la esperanza de que esto va a continuar expandi\u00e9ndose. Ahora tenemos cuatro carpetas en an\u00e1lisis y esperamos seguir ampli\u00e1ndolo\u201d, agreg\u00f3.<\/p>\n<p style=\"text-align: justify;\">Record\u00f3 que los cr\u00e9ditos hab\u00edan sido lanzados en agosto pasado tras el cierre de la cuarta convocatoria de becas autogestionadas.<\/p>\n<p style=\"text-align: justify;\">El tercer punto abordado durante la reuni\u00f3n informativa fue acerca de las bases y condiciones de la quinta convocatoria que est\u00e1 abierta hasta el 15 de noviembre, en la modalidad de becas autogestionadas de maestr\u00edas y doctorados.<\/p>\n<figure id=\"attachment_187169\" aria-describedby=\"caption-attachment-187169\" style=\"width: 336px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-187169\" src=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-_-Federico-Mora--600x376.jpg\" alt=\"\" width=\"336\" height=\"211\" srcset=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-_-Federico-Mora--600x376.jpg 600w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-_-Federico-Mora--768x481.jpg 768w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-_-Federico-Mora--696x436.jpg 696w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-_-Federico-Mora--671x420.jpg 671w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-_-BNF-_-Federico-Mora-.jpg 1000w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><figcaption id=\"caption-attachment-187169\" class=\"wp-caption-text\">Federico Mora, coordinador de Becal. Foto IP Paraguay<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Esta modalidad implica que el postulante debe acercarse a Becal una vez que cuente con admisi\u00f3n de la universidad, adem\u00e1s de la aceptaci\u00f3n del programa de estudios que desea desarrollar. Al respecto dijo que \u201clo que queremos es clarificar sobre los criterios de evaluaci\u00f3n y selecci\u00f3n que van a ser utilizados para la puntuaci\u00f3n de las diferentes postulaciones\u201d.<\/p>\n<p style=\"text-align: justify;\">Esto se realiza debido a que en la anterior convocatoria se tuvieron m\u00e1s de 600 postulantes, de los cuales solo el 10 por ciento fueron seleccionados, \u00a0y ante la necesidad de que el proceso \u201csea lo m\u00e1s transparente posible y brindar todas las calificaciones a aquellos que la requieran y quieran comprender el motivo de su selecci\u00f3n o no selecci\u00f3n\u201d, puntualiz\u00f3.<\/p>\n<p style=\"text-align: justify;\">La gu\u00eda de bases y condiciones en: <a href=\"http:\/\/www.becal.gov.py\/quinta-convocatoria\/\">http:\/\/www.becal.gov.py\/quinta-convocatoria\/<\/a>\u00a0.<\/p>\n<p style=\"text-align: justify;\">La idea es otorgar entre 20 a 25 becas que requerir\u00e1 de una inversi\u00f3n cerca a los 3 millones de dolares, manifest\u00f3 el titular de Becal.<\/p>\n<p style=\"text-align: justify;\"><strong>Becal benefici\u00f3 a m\u00e1s de 800 profesionales<\/strong><\/p>\n<p style=\"text-align: justify;\">Actualmente el programa cuenta actualmente con 886 becarios\/as de 27 pa\u00edses del mundo en las 300 mejores universidades seg\u00fan los rankings internacionales.<\/p>\n<p style=\"text-align: justify;\">Becal habilitar\u00e1 todos los viernes, del 22 de septiembre al 10 de noviembre, de 13:00 a 15:00, un espacio de reuni\u00f3n para quienes deseen acercarse a consultar.<\/p>\n<p style=\"text-align: justify;\">Asimismo, el tel\u00e9fono (021) 440 007 estar\u00e1 disponible para atenci\u00f3n de 8:00 a 15:00 de lunes a viernes, al igual que el email: <a href=\"mailto:consultasbecasenelexterior@hacienda.gov.py\">consultasbecasenelexterior@hacienda.gov.py<\/a> .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, IP.- El programa de becas \u00abCarlos Antonio L\u00f3pez\u00bb (Becal)\u00a0ampli\u00f3 el periodo de postulaci\u00f3n para Colombia, dirigido originalmente a docentes del sector oficial, extendiendo la oportunidad a docentes del sector privado- subvencionado.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":187167,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[166,536,39,1356],"class_list":{"0":"post-187187","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacado","8":"tag-becal","9":"tag-colombia","10":"tag-docentes","11":"tag-sector-privado-subvencionado"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Docentes del sector privado- subvencionado pueden postularse para becas a Colombia - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Docentes del sector privado- subvencionado pueden postularse para becas a Colombia - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, IP.- El programa de becas \u00abCarlos Antonio L\u00f3pez\u00bb (Becal)\u00a0ampli\u00f3 el periodo de postulaci\u00f3n para Colombia, dirigido originalmente a docentes del sector oficial, extendiendo la oportunidad a docentes del sector privado- subvencionado.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-28T15:55:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-BNF-financiaci\u00f3n-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"543\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"@dm1n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"@dm1n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/\"},\"author\":{\"name\":\"@dm1n\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/a1d87c4a65d7fd4ede9132995e2576d7\"},\"headline\":\"Docentes del sector privado- subvencionado pueden postularse para becas a Colombia\",\"datePublished\":\"2017-09-28T15:55:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/\"},\"wordCount\":641,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/BECAL-BNF-financiaci\u00f3n-.jpg\",\"keywords\":[\"Becal\",\"colombia\",\"Docentes\",\"Sector privado subvencionado\"],\"articleSection\":[\"Destacado\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/\",\"name\":\"Docentes del sector privado- subvencionado pueden postularse para becas a Colombia - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/BECAL-BNF-financiaci\u00f3n-.jpg\",\"datePublished\":\"2017-09-28T15:55:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/BECAL-BNF-financiaci\u00f3n-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/BECAL-BNF-financiaci\u00f3n-.jpg\",\"width\":1000,\"height\":543,\"caption\":\"En conferencia de prensa, Becal dio a conocer varias novedades relacionadas al programa. Foto IP Paraguay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2017\\\/09\\\/28\\\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docentes del sector privado- subvencionado pueden postularse para becas a Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Agencia-IP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Agencia-IP.jpg\",\"width\":150,\"height\":150,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/a1d87c4a65d7fd4ede9132995e2576d7\",\"name\":\"@dm1n\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/dm1n\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Docentes del sector privado- subvencionado pueden postularse para becas a Colombia - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/","og_locale":"es_ES","og_type":"article","og_title":"Docentes del sector privado- subvencionado pueden postularse para becas a Colombia - .::Agencia IP::.","og_description":"Asunci\u00f3n, IP.- El programa de becas \u00abCarlos Antonio L\u00f3pez\u00bb (Becal)\u00a0ampli\u00f3 el periodo de postulaci\u00f3n para Colombia, dirigido originalmente a docentes del sector oficial, extendiendo la oportunidad a docentes del sector privado- subvencionado.\u00a0","og_url":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2017-09-28T15:55:37+00:00","og_image":[{"width":1000,"height":543,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-BNF-financiaci\u00f3n-.jpg","type":"image\/jpeg"}],"author":"@dm1n","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"@dm1n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/"},"author":{"name":"@dm1n","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/a1d87c4a65d7fd4ede9132995e2576d7"},"headline":"Docentes del sector privado- subvencionado pueden postularse para becas a Colombia","datePublished":"2017-09-28T15:55:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/"},"wordCount":641,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-BNF-financiaci\u00f3n-.jpg","keywords":["Becal","colombia","Docentes","Sector privado subvencionado"],"articleSection":["Destacado"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/","url":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/","name":"Docentes del sector privado- subvencionado pueden postularse para becas a Colombia - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-BNF-financiaci\u00f3n-.jpg","datePublished":"2017-09-28T15:55:37+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-BNF-financiaci\u00f3n-.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2017\/09\/BECAL-BNF-financiaci\u00f3n-.jpg","width":1000,"height":543,"caption":"En conferencia de prensa, Becal dio a conocer varias novedades relacionadas al programa. Foto IP Paraguay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2017\/09\/28\/docentes-del-sector-privado-subvencionado-pueden-postularse-para-estudiar-en-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Docentes del sector privado- subvencionado pueden postularse para becas a Colombia"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2018\/01\/Agencia-IP.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2018\/01\/Agencia-IP.jpg","width":150,"height":150,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/a1d87c4a65d7fd4ede9132995e2576d7","name":"@dm1n","url":"https:\/\/www.ip.gov.py\/ip\/author\/dm1n\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/187187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=187187"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/187187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/187167"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=187187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=187187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=187187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}