{"id":340456,"date":"2020-10-30T11:06:23","date_gmt":"2020-10-30T14:06:23","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=340456"},"modified":"2020-10-30T11:14:14","modified_gmt":"2020-10-30T14:14:14","slug":"salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/","title":{"rendered":"Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Asunci\u00f3n, Paraguay, Agencia IP.- <\/em><\/strong>El ministro de Salud, Julio Mazzoleni, se\u00f1al\u00f3 que, en acordancia con la Iglesia Cat\u00f3lica, se insta a la ciudadan\u00eda a que las festividades por el D\u00eda de la Virgen de Caacup\u00e9 se celebren este a\u00f1o sin las peregrinaciones masivas que caracterizan a la fecha.<!--more--><\/p>\n<p style=\"text-align: justify;\">\u201cNuestro mensaje es que las fiestas marianas deben ser vividas en esta ocasi\u00f3n en las comunidades, o a trav\u00e9s de las m\u00faltiples plataformas virtuales que estar\u00e1n disponibles\u201d, dijo este viernes Mazzoleni en su reporte semanal sobre la situaci\u00f3n de covid-19.<\/p>\n<p style=\"text-align: justify;\">Indic\u00f3 que se convers\u00f3 con autoridades eclesi\u00e1sticas y las distintas parroquias e iglesias organizar\u00e1n encuentros. Adem\u00e1s la Virgen de Caacup\u00e9 peregrinar\u00e1 a distintas iglesias del pa\u00eds, luego de las celebraciones principales, para mantener la cercan\u00eda con los feligreses.<\/p>\n<p style=\"text-align: justify;\">El ministro afirm\u00f3 que se observar\u00e1n las semanas previas al 8 de diciembre, d\u00eda principal de las festividades, donde ya ocurren peregrinaciones de todo tipo y no se descarta suspender actividades presenciales.<\/p>\n<p style=\"text-align: justify;\">\u201cS\u00ed en esas semanas vemos alguna situaci\u00f3n que no condice con lo que se espera, est\u00e1 dentro de las posibilidades suspender las actividades presenciales para el d\u00eda 8 de diciembre\u201d, se\u00f1al\u00f3 el ministro.<\/p>\n<p style=\"text-align: justify;\">Durante esta semana fue presentado el <strong><a href=\"https:\/\/www.ip.gov.py\/ip\/presentan-protocolo-sanitario-para-operativo-caacupe-por-covid-19\/\">protocolo<\/a><\/strong> elaborado por el Ministerio y la Di\u00f3cesis de Caacup\u00e9, en donde se indica que las peregrinaciones tradicionales podr\u00e1n realizarse desde el 28 de noviembre al 4 de diciembre, previo agendamiento en un sitio web que se dar\u00e1 a conocer en los pr\u00f3ximos d\u00edas.<\/p>\n<p style=\"text-align: justify;\">Desde el 5 de diciembre y hasta el 8 se har\u00e1n las celebraciones eucar\u00edsticas, para las cuales tambi\u00e9n se requerir\u00e1 de agendamiento previo.<\/p>\n<p style=\"text-align: justify;\">En cuanto a las peregrinaciones, queda prohibida la participaci\u00f3n de adultos mayores de 60 a\u00f1os, mujeres embarazadas, ni\u00f1os menores de 12 a\u00f1os y personas con alguna condici\u00f3n cr\u00f3nica.<\/p>\n<p style=\"text-align: justify;\"><strong>Situaci\u00f3n epidemiol\u00f3gica<\/strong><\/p>\n<p style=\"text-align: justify;\">Sobre la situaci\u00f3n a nivel pa\u00eds con la pandemia, Mazzoleni indic\u00f3 que se mantiene la tendencia de \u201cmeseta\u201d, tras el \u00faltimo pico de casos hace 8 semanas.<\/p>\n<p style=\"text-align: justify;\">Los casos positivos se mantienen entre 5.000 a 5.700 por semana, siendo el departamento Central y Asunci\u00f3n los nuevos epicentros de la pandemia, con mayor aporte. El ministro se\u00f1al\u00f3 que se realiz\u00f3 una reuni\u00f3n con intendentes del departamento para ajustar medidas y concientizar a la ciudadan\u00eda en el cumplimiento de las medidas b\u00e1sicas.<\/p>\n<p style=\"text-align: justify;\">Destac\u00f3 tambi\u00e9n que Alto Paran\u00e1, que fue el primer epicentro de la pandemia a mediados de julio, hoy en d\u00eda tiene una cifra muy baja de casos y hasta el momento no se observa ninguna tendencia a la alza desde que se determin\u00f3 la apertura del Puente de la Amistad, hace dos semanas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Paraguay, Agencia IP.- El ministro de Salud, Julio Mazzoleni, se\u00f1al\u00f3 que, en acordancia con la Iglesia Cat\u00f3lica, se insta a la ciudadan\u00eda a que las festividades por el D\u00eda de la Virgen de Caacup\u00e9 se celebren este a\u00f1o sin las peregrinaciones masivas que caracterizan a la fecha.<\/p>\n","protected":false},"author":22,"featured_media":278900,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,6],"tags":[2985,1392],"class_list":["post-340456","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacado","category-politica","tag-covid-19","tag-virgen-de-caacupe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Paraguay, Agencia IP.- El ministro de Salud, Julio Mazzoleni, se\u00f1al\u00f3 que, en acordancia con la Iglesia Cat\u00f3lica, se insta a la ciudadan\u00eda a que las festividades por el D\u00eda de la Virgen de Caacup\u00e9 se celebren este a\u00f1o sin las peregrinaciones masivas que caracterizan a la fecha.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-30T14:06:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-30T14:14:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/07\/Caacupe-acceso-ruta-1-e1604066874735.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alberto C\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alberto C\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/\"},\"author\":{\"name\":\"Alberto C\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/369fedd28420fad35e23b10a9df16fb8\"},\"headline\":\"Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos\",\"datePublished\":\"2020-10-30T14:06:23+00:00\",\"dateModified\":\"2020-10-30T14:14:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/\"},\"wordCount\":478,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Caacupe-acceso-ruta-1-e1604066874735.jpg\",\"keywords\":[\"covid-19\",\"Virgen de Caacup\u00e9\"],\"articleSection\":[\"Destacado\",\"Pol\u00edtica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/\",\"name\":\"Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Caacupe-acceso-ruta-1-e1604066874735.jpg\",\"datePublished\":\"2020-10-30T14:06:23+00:00\",\"dateModified\":\"2020-10-30T14:14:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Caacupe-acceso-ruta-1-e1604066874735.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Caacupe-acceso-ruta-1-e1604066874735.jpg\",\"width\":1280,\"height\":854,\"caption\":\"Acceso a la ciudad de Caacup\u00e9. Foto Agencia IP.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2020\\\/10\\\/30\\\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/369fedd28420fad35e23b10a9df16fb8\",\"name\":\"Alberto C\",\"sameAs\":[\"https:\\\/\\\/www.ip.gov.py\"],\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/acelma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/","og_locale":"es_ES","og_type":"article","og_title":"Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos - .::Agencia IP::.","og_description":"Asunci\u00f3n, Paraguay, Agencia IP.- El ministro de Salud, Julio Mazzoleni, se\u00f1al\u00f3 que, en acordancia con la Iglesia Cat\u00f3lica, se insta a la ciudadan\u00eda a que las festividades por el D\u00eda de la Virgen de Caacup\u00e9 se celebren este a\u00f1o sin las peregrinaciones masivas que caracterizan a la fecha.","og_url":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2020-10-30T14:06:23+00:00","article_modified_time":"2020-10-30T14:14:14+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/07\/Caacupe-acceso-ruta-1-e1604066874735.jpg","type":"image\/jpeg"}],"author":"Alberto C","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Alberto C","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/"},"author":{"name":"Alberto C","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/369fedd28420fad35e23b10a9df16fb8"},"headline":"Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos","datePublished":"2020-10-30T14:06:23+00:00","dateModified":"2020-10-30T14:14:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/"},"wordCount":478,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/07\/Caacupe-acceso-ruta-1-e1604066874735.jpg","keywords":["covid-19","Virgen de Caacup\u00e9"],"articleSection":["Destacado","Pol\u00edtica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/","url":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/","name":"Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/07\/Caacupe-acceso-ruta-1-e1604066874735.jpg","datePublished":"2020-10-30T14:06:23+00:00","dateModified":"2020-10-30T14:14:14+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/07\/Caacupe-acceso-ruta-1-e1604066874735.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/07\/Caacupe-acceso-ruta-1-e1604066874735.jpg","width":1280,"height":854,"caption":"Acceso a la ciudad de Caacup\u00e9. Foto Agencia IP."},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2020\/10\/30\/salud-insta-a-celebraciones-por-la-virgen-de-caacupe-en-las-comunidades-y-sin-desplazamientos-masivos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Salud insta a celebraciones por la Virgen de Caacup\u00e9 en las comunidades y sin desplazamientos masivos"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/369fedd28420fad35e23b10a9df16fb8","name":"Alberto C","sameAs":["https:\/\/www.ip.gov.py"],"url":"https:\/\/www.ip.gov.py\/ip\/author\/acelma\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/340456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=340456"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/340456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/278900"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=340456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=340456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=340456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}