{"id":349505,"date":"2021-01-08T12:44:11","date_gmt":"2021-01-08T15:44:11","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=349505"},"modified":"2021-01-08T13:29:17","modified_gmt":"2021-01-08T16:29:17","slug":"paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/","title":{"rendered":"Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Asunci\u00f3n, Paraguay, Agencia IP.-<\/strong><\/em> El director de Paraguay Ciberseguro, Miguel \u00c1ngel Gaspar, dio a conocer una serie de recomendaciones ante los nuevos t\u00e9rminos de uso y pol\u00edticas de privacidad de WhatsApp para la recolecci\u00f3n de datos de los usuarios.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">En conversaci\u00f3n con <strong>Radio Nacional del Paraguay<\/strong>, Gaspar manifest\u00f3 que el anuncio de WhatsApp respecto a sus nuevas pol\u00edticas de privacidad represent\u00f3 una oportunidad para sembrar la importancia de valorizar y proteger los datos.<\/p>\n<p style=\"text-align: justify;\">En ese contexto, explic\u00f3 primeramente que tanto WhatsApp, Facebook y YouTube no son redes sociales sino que corresponden\u00a0 a un concepto de servicios que deben ser contratados mediante un acuerdo y una forma de pago. \u201cSi bien no estamos pagando con dinero, estamos pagando con nuestros datos\u201d, puntualiz\u00f3.<\/p>\n<p style=\"text-align: justify;\">Ante la uni\u00f3n de las mencionadas plataformas, Gaspar dijo que el anuncio es una oficializaci\u00f3n de la compa\u00f1\u00eda tecnol\u00f3gica de Mark Zuckerberg, aplicada tras la compra de Instagram y el canal de mensajer\u00eda.<\/p>\n<p style=\"text-align: justify;\">\u201cEntonces nuestros datos ahora ya no son dominio solamente de una de las aplicaciones sino de las tres y tambi\u00e9n de los asociados de negocios de estas plataformas\u201d, indic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Sobre el punto, inst\u00f3 a los usuarios a cuidar los datos que dan a conocer en estas herramientas digitales, a la que llam\u00f3 \u201chigiene digital\u201d, sugiriendo no llenar los dispositivos m\u00f3viles de informaciones sensibles.<\/p>\n<p style=\"text-align: justify;\">\u201cNo nos damos cuenta el grado de exposici\u00f3n porque hemos normalizado la hiperconectividad sin ning\u00fan tipo de l\u00edmites\u201d, se\u00f1al\u00f3. En esa l\u00ednea, recomend\u00f3 hacer una lista de aplicaciones que pueden ser desinstaladas y clasificar los c\u00edrculos sociales, laborales, profesionales y evaluar plataformas distintas en funci\u00f3n a la necesidad de privacidad.<\/p>\n<p style=\"text-align: justify;\">Otra de sus sugerencias es no tener abiertas y activas en un mismo dispositivo WhatsApp, Facebook e Instagram, sino utilizar de acuerdo a la demanda, dependiendo de la importancia de la informaci\u00f3n a ser compartida. Adem\u00e1s, aconsej\u00f3 utilizar otros servicios como Telegram, Signal o Confide.<\/p>\n<p style=\"text-align: justify;\">\u201cPedimos a la gente es no tener miedo, por sobre el miedo est\u00e1 la educaci\u00f3n y hay que entrenarse en el uso correcto de estas herramientas, valorar la privacidad y valorar los datos, la intimidad propia y la intimidad de la familia, ese entorno no hay que compartirlo en internet\u201d, expres\u00f3.<\/p>\n<h4 style=\"text-align: justify;\"><strong>La ciberdelincuencia en la regi\u00f3n aument\u00f3 en un 220 por ciento<\/strong><\/h4>\n<p style=\"text-align: justify;\">En otro momento, inform\u00f3 que a diferencia del promedio de la regi\u00f3n, que detalla que los usuarios abren el tel\u00e9fono unas 75 veces al d\u00eda, en Paraguay existen casos de 114 veces por d\u00eda.<\/p>\n<p style=\"text-align: justify;\">Dio a conocer adem\u00e1s que durante la pandemia covid-19 hubo un crecimiento de 220 por ciento de casos de ciberdelincuencia en la regi\u00f3n y ese porcentaje est\u00e1 sostenido en tres frentes: a la ni\u00f1ez y adolescencia, subsidios estatales, y cuentas de servicios como WhatsApp, Instagram y Facebook para extorsi\u00f3n o vaciamiento.<\/p>\n<p style=\"text-align: justify;\">\u201cEl foco de los ni\u00f1os es muy peligroso. En una peque\u00f1a encuesta que hicimos a final del \u00faltimo trimestre del 2020 hemos detectado que casi un 68 por ciento de la poblaci\u00f3n escolar que tuvo acceso a la conectividad fue abogada por terceras personas estando dentro de las plataformas que se utilizaron\u201d, detall\u00f3.<\/p>\n<p style=\"text-align: justify;\">En cuanto a la ciberdelincuencia en el pa\u00eds dijo que aproximadamente tuvo un crecimiento de entre 115 y 120 por ciento. \u00abEl trabajo de la tecnolog\u00eda es usarla con prop\u00f3sito pero cuando no hay un prop\u00f3sito, la gente se pierde y termina mal utiliz\u00e1ndola, sin darse cuenta llega a un proceso de ciberadicci\u00f3n\u201d, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Paraguay, Agencia IP.- El director de Paraguay Ciberseguro, Miguel \u00c1ngel Gaspar, dio a conocer una serie de recomendaciones ante los nuevos t\u00e9rminos de uso y pol\u00edticas de privacidad de WhatsApp para la recolecci\u00f3n de datos de los usuarios.<\/p>\n","protected":false},"author":31,"featured_media":349506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[4803,4805,4804],"class_list":["post-349505","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-ciberdelincuencia","tag-fundacion-paraguay-ciberseguro","tag-whatsapp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Paraguay, Agencia IP.- El director de Paraguay Ciberseguro, Miguel \u00c1ngel Gaspar, dio a conocer una serie de recomendaciones ante los nuevos t\u00e9rminos de uso y pol\u00edticas de privacidad de WhatsApp para la recolecci\u00f3n de datos de los usuarios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-08T15:44:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-08T16:29:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/01\/privacidad-seguridad-whatsapp-2188823.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Veronica Gimenez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Veronica Gimenez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/\"},\"author\":{\"name\":\"Veronica Gimenez\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/80dabd959b84f4db18b2b1a238d83e30\"},\"headline\":\"Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad\",\"datePublished\":\"2021-01-08T15:44:11+00:00\",\"dateModified\":\"2021-01-08T16:29:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/\"},\"wordCount\":612,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/privacidad-seguridad-whatsapp-2188823.jpg\",\"keywords\":[\"ciberdelincuencia\",\"Fundaci\u00f3n Paraguay Ciberseguro\",\"Whatsapp\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/\",\"name\":\"Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/privacidad-seguridad-whatsapp-2188823.jpg\",\"datePublished\":\"2021-01-08T15:44:11+00:00\",\"dateModified\":\"2021-01-08T16:29:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/privacidad-seguridad-whatsapp-2188823.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/privacidad-seguridad-whatsapp-2188823.jpg\",\"width\":480,\"height\":270,\"caption\":\"Durante la pandemia hubo un crecimiento de 220 por ciento de casos de ciberdelincuencia en la regi\u00f3n. Foto: Ilustraci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/01\\\/08\\\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/80dabd959b84f4db18b2b1a238d83e30\",\"name\":\"Veronica Gimenez\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/vgimenez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad - .::Agencia IP::.","og_description":"Asunci\u00f3n, Paraguay, Agencia IP.- El director de Paraguay Ciberseguro, Miguel \u00c1ngel Gaspar, dio a conocer una serie de recomendaciones ante los nuevos t\u00e9rminos de uso y pol\u00edticas de privacidad de WhatsApp para la recolecci\u00f3n de datos de los usuarios.","og_url":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2021-01-08T15:44:11+00:00","article_modified_time":"2021-01-08T16:29:17+00:00","og_image":[{"width":480,"height":270,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/01\/privacidad-seguridad-whatsapp-2188823.jpg","type":"image\/jpeg"}],"author":"Veronica Gimenez","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Veronica Gimenez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/"},"author":{"name":"Veronica Gimenez","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/80dabd959b84f4db18b2b1a238d83e30"},"headline":"Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad","datePublished":"2021-01-08T15:44:11+00:00","dateModified":"2021-01-08T16:29:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/"},"wordCount":612,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/01\/privacidad-seguridad-whatsapp-2188823.jpg","keywords":["ciberdelincuencia","Fundaci\u00f3n Paraguay Ciberseguro","Whatsapp"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/","url":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/","name":"Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/01\/privacidad-seguridad-whatsapp-2188823.jpg","datePublished":"2021-01-08T15:44:11+00:00","dateModified":"2021-01-08T16:29:17+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/01\/privacidad-seguridad-whatsapp-2188823.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/01\/privacidad-seguridad-whatsapp-2188823.jpg","width":480,"height":270,"caption":"Durante la pandemia hubo un crecimiento de 220 por ciento de casos de ciberdelincuencia en la regi\u00f3n. Foto: Ilustraci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2021\/01\/08\/paraguay-ciberseguro-recomienda-sobre-uso-de-whatsappa-ante-nuevas-politicas-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Brindan recomendaciones sobre uso de WhatsApp ante nuevas pol\u00edticas de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/80dabd959b84f4db18b2b1a238d83e30","name":"Veronica Gimenez","url":"https:\/\/www.ip.gov.py\/ip\/author\/vgimenez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/349505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=349505"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/349505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/349506"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=349505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=349505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=349505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}