{"id":369235,"date":"2021-06-11T07:13:49","date_gmt":"2021-06-11T11:13:49","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=369235"},"modified":"2021-06-11T08:32:59","modified_gmt":"2021-06-11T12:32:59","slug":"mopc-inicia-auditoria-de-todos-los-puentes-del-pais","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/","title":{"rendered":"MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Asunci\u00f3n, Agencia IP.-<\/strong> <\/em>El Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC) inicia una auditor\u00eda interna de todos los puentes construidos en rutas a nivel pa\u00eds. <!--more--><\/p>\n<p style=\"text-align: justify;\">As\u00ed tambi\u00e9n la instituci\u00f3n inform\u00f3 que acompa\u00f1ar\u00e1 todas las diligencias que considere pertinentes el Ministerio P\u00fablico para esclarecer el lamentable suceso ocurrido tras el derrumbe de un puente de hormig\u00f3n armado en el departamento de San Pedro.<\/p>\n<p style=\"text-align: justify;\">Mediante Resoluci\u00f3n N\u00b0 1152\/21, el ministro de la cartera de Obras, Arnoldo Wiens, dispuso iniciar una auditor\u00eda interna de todos los puentes de hormig\u00f3n armado, madera y met\u00e1lico, construidos en rutas nacionales, departamentales, as\u00ed como en caminos vecinales de todos los departamentos de la Rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">Para dicho efecto, orden\u00f3 a la Direcci\u00f3n de Auditor\u00eda Interna de la instituci\u00f3n, a trav\u00e9s de sus reparticiones pertinentes, la tramitaci\u00f3n para el cumplimiento de lo dispuesto en la resoluci\u00f3n.<\/p>\n<p><strong>Ministro Wiens expres\u00f3 que est\u00e1n a disposici\u00f3n del Ministerio P\u00fablico<\/strong><\/p>\n<figure id=\"attachment_369241\" aria-describedby=\"caption-attachment-369241\" style=\"width: 350px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-369241\" src=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/06\/MOPC-Puente-600x400.jpeg\" alt=\"\" width=\"350\" height=\"233\" srcset=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/06\/MOPC-Puente-600x400.jpeg 600w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/06\/MOPC-Puente-1024x683.jpeg 1024w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/06\/MOPC-Puente-768x512.jpeg 768w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/06\/MOPC-Puente-696x464.jpeg 696w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/06\/MOPC-Puente-1068x712.jpeg 1068w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/06\/MOPC-Puente-630x420.jpeg 630w, https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/06\/MOPC-Puente.jpeg 1200w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><figcaption id=\"caption-attachment-369241\" class=\"wp-caption-text\">El titular de Obras P\u00fablicas, Arnoldo Wiens, lleg\u00f3 este jueves a la zona del derrumbe del puente de hormig\u00f3n ubicado en la zona de Tacuat\u00ed, departamento de San Pedro Foto: MOPC<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El titular de Obras P\u00fablicas, Arnoldo Wiens, lleg\u00f3 este jueves a la zona del derrumbe del puente de hormig\u00f3n ubicado en la zona de Tacuat\u00ed, departamento de San Pedro, donde entre otras cosas, dijo que est\u00e1n a disposici\u00f3n del Ministerio P\u00fablico para la investigaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Indic\u00f3 que su presencia en el lugar es para verificar in situ la situaci\u00f3n, y aprovechar para expresar las condolencias a los familiares de las v\u00edctimas de este tr\u00e1gico suceso.<\/p>\n<p style=\"text-align: justify;\">Reiter\u00f3 que este puente fue construido hace 20 a\u00f1os, y que el tramo posteriormente fue empedrado en otra administraci\u00f3n para convertirse finalmente en un asfaltado.<\/p>\n<p style=\"text-align: justify;\">Sobre las acciones inmediatas, mencion\u00f3 que ya se inici\u00f3 una auditor\u00eda interna, a cargo del Ing. Paulo Yugovich, quien es pat\u00f3logo y especialista en estructuras de hormig\u00f3n, adem\u00e1s de una auditor\u00eda de todos los puentes del pa\u00eds para determinar en qu\u00e9 situaci\u00f3n se encuentran, de manera a que, en lo posible, se puede evitar otras desgracias similares.<\/p>\n<p style=\"text-align: justify;\">Insisti\u00f3 en que su administraci\u00f3n acompa\u00f1ar\u00e1 todas las diligencias que considere pertinentes el Ministerio P\u00fablico, por lo cual ya est\u00e1n recabando toda la informaci\u00f3n posible de manera a deslindar responsabilidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Agencia IP.- El Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC) inicia una auditor\u00eda interna de todos los puentes construidos en rutas a nivel pa\u00eds.<\/p>\n","protected":false},"author":23,"featured_media":42923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,4],"tags":[6392,97,399],"class_list":["post-369235","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacado","category-nacionales","tag-auditoria","tag-mopc","tag-puentes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Agencia IP.- El Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC) inicia una auditor\u00eda interna de todos los puentes construidos en rutas a nivel pa\u00eds.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-11T11:13:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-11T12:32:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/08\/puentesobrejejui_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noelia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noelia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/\"},\"author\":{\"name\":\"Noelia Ferreira\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/791af27a9219bdbf9064abb776bb41c2\"},\"headline\":\"MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds\",\"datePublished\":\"2021-06-11T11:13:49+00:00\",\"dateModified\":\"2021-06-11T12:32:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/\"},\"wordCount\":429,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/puentesobrejejui_.jpg\",\"keywords\":[\"Auditoria\",\"MOPC\",\"Puentes\"],\"articleSection\":[\"Destacado\",\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/\",\"name\":\"MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/puentesobrejejui_.jpg\",\"datePublished\":\"2021-06-11T11:13:49+00:00\",\"dateModified\":\"2021-06-11T12:32:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/puentesobrejejui_.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/puentesobrejejui_.jpg\",\"width\":600,\"height\":336,\"caption\":\"Foto Ilustraci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2021\\\/06\\\/11\\\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/791af27a9219bdbf9064abb776bb41c2\",\"name\":\"Noelia Ferreira\",\"sameAs\":[\"http:\\\/\\\/www.ip.gov.py\"],\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/nferreira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/","og_locale":"es_ES","og_type":"article","og_title":"MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds - .::Agencia IP::.","og_description":"Asunci\u00f3n, Agencia IP.- El Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC) inicia una auditor\u00eda interna de todos los puentes construidos en rutas a nivel pa\u00eds.","og_url":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2021-06-11T11:13:49+00:00","article_modified_time":"2021-06-11T12:32:59+00:00","og_image":[{"width":600,"height":336,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/08\/puentesobrejejui_.jpg","type":"image\/jpeg"}],"author":"Noelia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Noelia Ferreira","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/"},"author":{"name":"Noelia Ferreira","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/791af27a9219bdbf9064abb776bb41c2"},"headline":"MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds","datePublished":"2021-06-11T11:13:49+00:00","dateModified":"2021-06-11T12:32:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/"},"wordCount":429,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/08\/puentesobrejejui_.jpg","keywords":["Auditoria","MOPC","Puentes"],"articleSection":["Destacado","Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/","url":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/","name":"MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/08\/puentesobrejejui_.jpg","datePublished":"2021-06-11T11:13:49+00:00","dateModified":"2021-06-11T12:32:59+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/08\/puentesobrejejui_.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/08\/puentesobrejejui_.jpg","width":600,"height":336,"caption":"Foto Ilustraci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2021\/06\/11\/mopc-inicia-auditoria-de-todos-los-puentes-del-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"MOPC inicia auditor\u00eda de todos los puentes del pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/791af27a9219bdbf9064abb776bb41c2","name":"Noelia Ferreira","sameAs":["http:\/\/www.ip.gov.py"],"url":"https:\/\/www.ip.gov.py\/ip\/author\/nferreira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/369235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=369235"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/369235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/42923"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=369235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=369235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=369235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}