{"id":399379,"date":"2022-01-10T13:17:11","date_gmt":"2022-01-10T16:17:11","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=399379"},"modified":"2022-01-10T16:53:58","modified_gmt":"2022-01-10T19:53:58","slug":"mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/","title":{"rendered":"M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Asunci\u00f3n, Agencia IP.-<\/strong> <\/em>En los \u00faltimos a\u00f1os, Paraguay adopt\u00f3 pol\u00edticas favorables hacia los negocios lo cual ha despertado el inter\u00e9s de unas 28 empresas extranjeras que quieren instalarse en el pa\u00eds. El potencial de inversi\u00f3n es de 5.000 millones de d\u00f3lares.<!--more--><\/p>\n<p style=\"text-align: justify;\">El presidente de la Rep\u00fablica, <a href=\"https:\/\/www.ip.gov.py\/ip\/presidente-inicia-visita-tecnicas-a-ministerios-y-resalta-clima-de-negocios-del-pais\/\" target=\"_blank\" rel=\"noopener\"><strong>Mario Abdo Ben\u00edtez, encabez\u00f3 una reuni\u00f3n de trabajo<\/strong><\/a> realizada en el Ministerio de Industria y Comercio (MIC), ocasi\u00f3n en que las autoridades hicieron un repaso acerca de los principales indicadores econ\u00f3micos y de los rubros de exportaci\u00f3n del pa\u00eds, que dan cuenta de un proceso de transformaci\u00f3n de la econom\u00eda nacional.<\/p>\n<p style=\"text-align: justify;\">Al finalizar el encuentro, el titular del MIC, Luis Castiglioni, coment\u00f3 que existen unas 28 empresas de diversas partes del mundo interesadas en instalarse en el pa\u00eds en los pr\u00f3ximos a\u00f1os, cuyas inversiones superan los 5.000 millones de d\u00f3lares.<\/p>\n<p style=\"text-align: justify;\">\u201cSon n\u00fameros que no se conoc\u00edan y est\u00e1 en consonancia con nuestra filosof\u00eda de que el sector privados e convierta en el principal herramienta de creaci\u00f3n de riqueza y desarrollo\u201d, agreg\u00f3 el ministro.<\/p>\n<p style=\"text-align: justify;\">En esa misma l\u00ednea coment\u00f3 que el ambiente amigable para los negocios, previsibilidad macroecon\u00f3mica y financiera, disciplina monetaria, los incentivos a la inversi\u00f3n y la ventajosa ubicaci\u00f3n geogr\u00e1fica, son las principales herramientas que han llamado la atenci\u00f3n de los potenciales inversionistas expuestos anteriormente.<\/p>\n<p style=\"text-align: justify;\">Asimismo inform\u00f3 que actualmente la Red de Inversiones y Exportaciones (Rediex) est\u00e1 haciendo un seguimiento a cada una de las firmas para interiorizarse respecto a las expectativas, facilidades y exigencias que requieren las mismas para venir a suelo guaran\u00ed. \u201cLes estamos dando el acompa\u00f1amiento permanente hasta que se concrete\u201d, remarc\u00f3.<\/p>\n<p style=\"text-align: justify;\">Al respecto, precis\u00f3 que est\u00e1n avanzadas las gestiones para que Marfrig, l\u00edder mundial en la producci\u00f3n de hamburguesas pueda construir su primera planta industrial en Paraguay en la ciudad de Yby Ya\u00fa, en Concepci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Asimismo habl\u00f3 del proyecto de asentar una planta ensambladora de aviones de alta tecnolog\u00eda, gracias a la articulaci\u00f3n con el Ministerio de Defensa, las Fuerzas Armadas y la Direcci\u00f3n de Aeron\u00e1utica Civil (Dinac).<\/p>\n<p style=\"text-align: justify;\">\u201cLa industria se va asentar en el aeropuerto Guaran\u00ed y seg\u00fan los inversionistas entre finales de enero y principios de febrero comenzar\u00edan la instalaci\u00f3n de la planta industrial\u201d, indic\u00f3 al tiempo de resaltar que ello, implica un gran salto para el pa\u00eds.<\/p>\n<h5 style=\"text-align: justify;\"><strong>Acerca de otros datos:<\/strong><\/h5>\n<p style=\"text-align: justify;\">En el 2021, la industria de la maquila permiti\u00f3 la creaci\u00f3n de 3.286 nuevos puestos de trabajo.<\/p>\n<p style=\"text-align: justify;\">Por primera vez las exportaciones industriales del r\u00e9gimen de maquila alcanzaron USD 881 millones y crecieron 54% en relaci\u00f3n con el 2020.<\/p>\n<p style=\"text-align: justify;\">La Ley de Empresas por Acciones Simplificadas (EAS) permiti\u00f3 la creaci\u00f3n de 1000 empresas en el 2021.<\/p>\n<p style=\"text-align: justify;\">Durante el a\u00f1o 2021 se registraron exportaciones por valor de 8.421,8 millones de d\u00f3lares (excluyendo el rubro energ\u00eda el\u00e9ctrica). Esta cifra, comparada con las del a\u00f1o 2020 (6.305,6 millones de d\u00f3lares), revela un crecimiento de las exportaciones en 33,6%.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s 23 tipos de productos exportados en 2021 sobrepasaron el umbral de 50 millones de d\u00f3lares, correspondientes a las partidas \u201cdem\u00e1s grasas y aceites\u201d, \u201csalvados\u201d, \u201cmanufacturas de aluminio\u201d, \u201cmedicamentos\u201d, \u201cgrasa bovina\u201d y \u201cpapeles y cartones\u201d.<\/p>\n<p style=\"text-align: justify;\">Los registros del MIC, a trav\u00e9s de Rediex, muestran que en el 2021, en cuanto a la Inversi\u00f3n Directa Extranjera (IED), se identificaron 19 empresas nuevas que han iniciado la instalaci\u00f3n operativa o jur\u00eddica para echar a andar emprendimientos productivos, que crear\u00e1n 41.983 nuevos puestos de trabajo.<\/p>\n<p style=\"text-align: justify;\">En el 2021, 28 empresas de Argentina (6), Australia (1), Brasil (9), Canad\u00e1 (1), Corea del Sur (1), Espa\u00f1a (4), India\/Argentina\/Canad\u00e1 (1), Reino Unido (1), Italia (1), Per\u00fa (1), Taiw\u00e1n (1), Turqu\u00eda (1), han exteriorizado su decisi\u00f3n de invertir en el Paraguay en los pr\u00f3ximos meses.<\/p>\n<p style=\"text-align: justify;\">Dichas inversiones se registrar\u00edan en diversos sectores, previ\u00e9ndose su localizaci\u00f3n en diversos puntos de la geograf\u00eda nacional. Un total de 15.720 nuevos puestos ser\u00edan creados parea la operatoria de estas actividades.<\/p>\n<p style=\"text-align: justify;\">Finalmente el titular del MIC se comprometi\u00f3 a seguir trabajando para que el Paraguay se ponga a la cabeza del crecimiento econ\u00f3mico en Am\u00e9rica Latina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Agencia IP.- En los \u00faltimos a\u00f1os, Paraguay adopt\u00f3 pol\u00edticas favorables hacia los negocios lo cual ha despertado el inter\u00e9s de unas 28 empresas extranjeras que quieren instalarse en el pa\u00eds. El potencial de inversi\u00f3n es de 5.000 millones de d\u00f3lares.<\/p>\n","protected":false},"author":7,"featured_media":399394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,6],"tags":[3632,5332,3292],"class_list":["post-399379","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacado","category-politica","tag-luis-castiglioni","tag-ministerio-de-industria-y-comercio","tag-presidente-abdo-benitez"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Agencia IP.- En los \u00faltimos a\u00f1os, Paraguay adopt\u00f3 pol\u00edticas favorables hacia los negocios lo cual ha despertado el inter\u00e9s de unas 28 empresas extranjeras que quieren instalarse en el pa\u00eds. El potencial de inversi\u00f3n es de 5.000 millones de d\u00f3lares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-10T16:17:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-10T19:53:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/01\/luis-castiglioni-mic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karina L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karina L\u00f3pez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/\"},\"author\":{\"name\":\"Karina L\u00f3pez\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/613765cf13d420d448042e6802220539\"},\"headline\":\"M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay\",\"datePublished\":\"2022-01-10T16:17:11+00:00\",\"dateModified\":\"2022-01-10T19:53:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/\"},\"wordCount\":709,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/luis-castiglioni-mic.jpg\",\"keywords\":[\"Luis Castiglioni\",\"Ministerio de Industria y Comercio\",\"Presidente Abdo Ben\u00edtez\"],\"articleSection\":[\"Destacado\",\"Pol\u00edtica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/\",\"name\":\"M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/luis-castiglioni-mic.jpg\",\"datePublished\":\"2022-01-10T16:17:11+00:00\",\"dateModified\":\"2022-01-10T19:53:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/luis-castiglioni-mic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/luis-castiglioni-mic.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"Luis Castiglioni, ministro de Industria y Comercio.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/10\\\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/613765cf13d420d448042e6802220539\",\"name\":\"Karina L\u00f3pez\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/klopez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay - .::Agencia IP::.","og_description":"Asunci\u00f3n, Agencia IP.- En los \u00faltimos a\u00f1os, Paraguay adopt\u00f3 pol\u00edticas favorables hacia los negocios lo cual ha despertado el inter\u00e9s de unas 28 empresas extranjeras que quieren instalarse en el pa\u00eds. El potencial de inversi\u00f3n es de 5.000 millones de d\u00f3lares.","og_url":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2022-01-10T16:17:11+00:00","article_modified_time":"2022-01-10T19:53:58+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/01\/luis-castiglioni-mic.jpg","type":"image\/jpeg"}],"author":"Karina L\u00f3pez","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Karina L\u00f3pez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/"},"author":{"name":"Karina L\u00f3pez","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/613765cf13d420d448042e6802220539"},"headline":"M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay","datePublished":"2022-01-10T16:17:11+00:00","dateModified":"2022-01-10T19:53:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/"},"wordCount":709,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/01\/luis-castiglioni-mic.jpg","keywords":["Luis Castiglioni","Ministerio de Industria y Comercio","Presidente Abdo Ben\u00edtez"],"articleSection":["Destacado","Pol\u00edtica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/","url":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/","name":"M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/01\/luis-castiglioni-mic.jpg","datePublished":"2022-01-10T16:17:11+00:00","dateModified":"2022-01-10T19:53:58+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/01\/luis-castiglioni-mic.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/01\/luis-castiglioni-mic.jpg","width":1600,"height":1067,"caption":"Luis Castiglioni, ministro de Industria y Comercio."},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/10\/mas-de-una-veintena-de-firmas-extranjeras-interesadas-en-invertir-unos-us-5-000-millones-en-paraguay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de una veintena de firmas extranjeras interesadas en invertir unos US$ 5.000 millones en Paraguay"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/613765cf13d420d448042e6802220539","name":"Karina L\u00f3pez","url":"https:\/\/www.ip.gov.py\/ip\/author\/klopez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/399379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=399379"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/399379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/399394"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=399379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=399379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=399379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}