{"id":400717,"date":"2022-01-23T16:37:01","date_gmt":"2022-01-23T19:37:01","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=400717"},"modified":"2022-01-23T16:38:11","modified_gmt":"2022-01-23T19:38:11","slug":"test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/","title":{"rendered":"Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Asunci\u00f3n, Agencia IP.-<\/strong> <\/em>Tres puestos de toma de muestra para la prueba de covid por ant\u00edgeno sin agendamiento fueron habilitados por el Ministerio de Salud P\u00fablica.<!--more--><\/p>\n<p style=\"text-align: justify;\">Ante el aumento de la variante \u00f3micron en la poblaci\u00f3n y a fin de que la ciudadan\u00eda cuente con m\u00e1s facilidades para realizarse la prueba de covid-19, la cartera sanitaria habilit\u00f3 tres puntos de toma de muestra para pacientes que cuenten con 2 a 4 d\u00edas de s\u00edntomas.<\/p>\n<p style=\"text-align: justify;\">El \u00fanico puesto de toma de muestra peatonal se realiza en el <strong>Polideportivo del Colegio Salesiano<\/strong>, sitio Manuel Dom\u00ednguez y Brasil de la ciudad de Asunci\u00f3n de lunes a domingo en el horario de 07:00 a 16:00.<\/p>\n<p style=\"text-align: justify;\">En la <strong>Costanera Jos\u00e9 Asunci\u00f3n Flores de Asunci\u00f3n<\/strong> la toma de muestra se realiza de manera vehicular de lunes a domingo de 08:00 a 18:00.<\/p>\n<p style=\"text-align: justify;\">Y en el <strong>Aut\u00f3dromo Rub\u00e9n Dumot<\/strong> (exAratiri) de la ciudad de Capiat\u00e1 en la modalidad vehicular de lunes a viernes 07:00 a 22:00 y los s\u00e1bados y domingos de 07:00 a 17:00.<\/p>\n<p style=\"text-align: justify;\">La cartera de Salud recuerda que las pruebas por el m\u00e9todo PCR se realizan a trav\u00e9s de la l\u00ednea 154.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Agencia IP.- Tres puestos de toma de muestra para la prueba de covid por ant\u00edgeno sin agendamiento fueron habilitados por el Ministerio de Salud P\u00fablica.<\/p>\n","protected":false},"author":23,"featured_media":328493,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,4],"tags":[9565,10289,10153,91],"class_list":["post-400717","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacado","category-nacionales","tag-antigeno","tag-polideportivo-colegio-salesiano","tag-prueba-covid","tag-salud-publica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Agencia IP.- Tres puestos de toma de muestra para la prueba de covid por ant\u00edgeno sin agendamiento fueron habilitados por el Ministerio de Salud P\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-23T19:37:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-23T19:38:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2020\/08\/toma-de-muestras.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"956\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noelia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noelia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/\"},\"author\":{\"name\":\"Noelia Ferreira\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/791af27a9219bdbf9064abb776bb41c2\"},\"headline\":\"Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras\",\"datePublished\":\"2022-01-23T19:37:01+00:00\",\"dateModified\":\"2022-01-23T19:38:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/\"},\"wordCount\":212,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/toma-de-muestras.jpg\",\"keywords\":[\"ant\u00edgeno\",\"Polideportivo Colegio Salesiano\",\"Prueba covid\",\"Salud P\u00fablica\"],\"articleSection\":[\"Destacado\",\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/\",\"name\":\"Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/toma-de-muestras.jpg\",\"datePublished\":\"2022-01-23T19:37:01+00:00\",\"dateModified\":\"2022-01-23T19:38:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/toma-de-muestras.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/toma-de-muestras.jpg\",\"width\":870,\"height\":956,\"caption\":\"Foto Ministerio de Salud P\u00fablica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/01\\\/23\\\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/791af27a9219bdbf9064abb776bb41c2\",\"name\":\"Noelia Ferreira\",\"sameAs\":[\"http:\\\/\\\/www.ip.gov.py\"],\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/nferreira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/","og_locale":"es_ES","og_type":"article","og_title":"Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras - .::Agencia IP::.","og_description":"Asunci\u00f3n, Agencia IP.- Tres puestos de toma de muestra para la prueba de covid por ant\u00edgeno sin agendamiento fueron habilitados por el Ministerio de Salud P\u00fablica.","og_url":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2022-01-23T19:37:01+00:00","article_modified_time":"2022-01-23T19:38:11+00:00","og_image":[{"width":870,"height":956,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2020\/08\/toma-de-muestras.jpg","type":"image\/jpeg"}],"author":"Noelia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Noelia Ferreira","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/"},"author":{"name":"Noelia Ferreira","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/791af27a9219bdbf9064abb776bb41c2"},"headline":"Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras","datePublished":"2022-01-23T19:37:01+00:00","dateModified":"2022-01-23T19:38:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/"},"wordCount":212,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2020\/08\/toma-de-muestras.jpg","keywords":["ant\u00edgeno","Polideportivo Colegio Salesiano","Prueba covid","Salud P\u00fablica"],"articleSection":["Destacado","Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/","url":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/","name":"Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2020\/08\/toma-de-muestras.jpg","datePublished":"2022-01-23T19:37:01+00:00","dateModified":"2022-01-23T19:38:11+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2020\/08\/toma-de-muestras.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2020\/08\/toma-de-muestras.jpg","width":870,"height":956,"caption":"Foto Ministerio de Salud P\u00fablica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/01\/23\/test-antigeno-para-covid-19-se-realiza-sin-agendamiento-en-tres-puestos-de-toma-de-muestras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Test ant\u00edgeno para covid-19 se realiza sin agendamiento en tres puestos de toma de muestras"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/791af27a9219bdbf9064abb776bb41c2","name":"Noelia Ferreira","sameAs":["http:\/\/www.ip.gov.py"],"url":"https:\/\/www.ip.gov.py\/ip\/author\/nferreira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/400717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=400717"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/400717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/328493"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=400717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=400717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=400717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}