{"id":408106,"date":"2022-03-16T09:44:49","date_gmt":"2022-03-16T12:44:49","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=408106"},"modified":"2022-03-16T10:05:22","modified_gmt":"2022-03-16T13:05:22","slug":"el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/","title":{"rendered":"Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Asunci\u00f3n, Agencia IP.-<\/strong> <\/em>Paraguay actualmente se encuentra importando el 95% de los productos frutihort\u00edcolas ya que a causa de la prolongada sequ\u00eda y las altas temperaturas registradas los agricultores no pudieron sacar productos de calidad y en cantidad para satisfacer la demanda nacional. <!--more--><\/p>\n<p style=\"text-align: justify;\">El director de Comercializaci\u00f3n del Ministerio de Agricultura y Ganader\u00eda (MAG), Ernesto Sotelo, inform\u00f3 que actualmente en el campo tras las lluvias que se registraron en el \u00faltimo mes, se iniciaron las cosechas de productos frutihort\u00edcolas pero que este a\u00f1o la producci\u00f3n no cubrir\u00e1 la demanda del mercado nacional a causa de la situaci\u00f3n que se gener\u00f3 tras la larga sequ\u00eda.<\/p>\n<p style=\"text-align: justify;\">En ese sentido refiri\u00f3 que para cubrir la demanda el MAG deber\u00e1 expedir a su tiempo el permiso de exportaci\u00f3n de ciertos productos prioritarios como son el tomate, pimiento, cebolla, papa, zanahoria.<\/p>\n<p style=\"text-align: justify;\">\u00abEste permiso se da a trav\u00e9s de los informes que la Direcci\u00f3n de Comercializaci\u00f3n presenta sobre la disponibilidad de estos rubros y si hay necesidad se procede a la extensi\u00f3n de los permisos de importaci\u00f3n para satisfacer la demanda de los rubros que se requieren\u00bb, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">En cuanto al tomate precis\u00f3 que el consumo diario nacional asciende a 200 toneladas y que actualmente esa necesidad no es satisfecha, por lo que se permite la importaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En tanto que la cebolla refiri\u00f3 que termin\u00f3 el periodo de producci\u00f3n de cebollas que va desde la segunda quincena de septiembre y se extiende hasta diciembre. \u00abEsos son los meses que se disponen de cebolla nacional en el mercado interno, posteriormente por supuesto hay que permitir nuevamente la importaci\u00f3n de este rubro\u00bb, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Asegur\u00f3 que actualmente el 95% de los productos frutihort\u00edcolas est\u00e1n siendo importados en el pa\u00eds. \u00abEstuvimos esta ma\u00f1ana por el Mercado de Abasto y vimos el panorama y tuvimos el reflejo de lo que es actualmente el campo y podemos decir que no hay producci\u00f3n de origen nacional\u00bb, reiter\u00f3 en entrevista con Radio Nacional del Paraguay.<\/p>\n<h4 style=\"text-align: justify;\"><strong>Inicia siembra de verdeos<\/strong><\/h4>\n<p style=\"text-align: justify;\">Sotelo sostuvo que actualmente los agricultores y productores ya se encuentran sembrando y en algunos casos cosechando rubros de verdeos, como son cebollita, lechuga, perejil, entre otras hortalizas.<\/p>\n<p style=\"text-align: justify;\">\u00abEso disponemos de a poco, pero eso se ir\u00e1 incrementando con el tiempo, te puedo asegurar que de aqu\u00ed a dos meses podemos decir que tendremos una buena producci\u00f3n\u00bb, refiri\u00f3 finalmente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Agencia IP.- Paraguay actualmente se encuentra importando el 95% de los productos frutihort\u00edcolas ya que a causa de la prolongada sequ\u00eda y las altas temperaturas registradas los agricultores no pudieron sacar productos de calidad y en cantidad para satisfacer la demanda nacional.<\/p>\n","protected":false},"author":23,"featured_media":397634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[4895,128,59,2014,11054],"class_list":["post-408106","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia","tag-direccion-de-comercializacion","tag-importacion","tag-mag","tag-siembra","tag-verdeos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Agencia IP.- Paraguay actualmente se encuentra importando el 95% de los productos frutihort\u00edcolas ya que a causa de la prolongada sequ\u00eda y las altas temperaturas registradas los agricultores no pudieron sacar productos de calidad y en cantidad para satisfacer la demanda nacional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-16T12:44:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-16T13:05:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/12\/Venta-naranja-Mercado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"692\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noelia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noelia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/\"},\"author\":{\"name\":\"Noelia Ferreira\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/791af27a9219bdbf9064abb776bb41c2\"},\"headline\":\"Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas\",\"datePublished\":\"2022-03-16T12:44:49+00:00\",\"dateModified\":\"2022-03-16T13:05:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/\"},\"wordCount\":424,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Venta-naranja-Mercado.jpg\",\"keywords\":[\"Direcci\u00f3n de Comercializaci\u00f3n\",\"importaci\u00f3n\",\"MAG\",\"siembra\",\"verdeos\"],\"articleSection\":[\"Econom\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/\",\"name\":\"Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Venta-naranja-Mercado.jpg\",\"datePublished\":\"2022-03-16T12:44:49+00:00\",\"dateModified\":\"2022-03-16T13:05:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Venta-naranja-Mercado.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Venta-naranja-Mercado.jpg\",\"width\":1040,\"height\":692,\"caption\":\"Foto: Agencia IP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/03\\\/16\\\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/791af27a9219bdbf9064abb776bb41c2\",\"name\":\"Noelia Ferreira\",\"sameAs\":[\"http:\\\/\\\/www.ip.gov.py\"],\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/nferreira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/","og_locale":"es_ES","og_type":"article","og_title":"Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas - .::Agencia IP::.","og_description":"Asunci\u00f3n, Agencia IP.- Paraguay actualmente se encuentra importando el 95% de los productos frutihort\u00edcolas ya que a causa de la prolongada sequ\u00eda y las altas temperaturas registradas los agricultores no pudieron sacar productos de calidad y en cantidad para satisfacer la demanda nacional.","og_url":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2022-03-16T12:44:49+00:00","article_modified_time":"2022-03-16T13:05:22+00:00","og_image":[{"width":1040,"height":692,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/12\/Venta-naranja-Mercado.jpg","type":"image\/jpeg"}],"author":"Noelia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Noelia Ferreira","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/"},"author":{"name":"Noelia Ferreira","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/791af27a9219bdbf9064abb776bb41c2"},"headline":"Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas","datePublished":"2022-03-16T12:44:49+00:00","dateModified":"2022-03-16T13:05:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/"},"wordCount":424,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/12\/Venta-naranja-Mercado.jpg","keywords":["Direcci\u00f3n de Comercializaci\u00f3n","importaci\u00f3n","MAG","siembra","verdeos"],"articleSection":["Econom\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/","url":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/","name":"Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/12\/Venta-naranja-Mercado.jpg","datePublished":"2022-03-16T12:44:49+00:00","dateModified":"2022-03-16T13:05:22+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/12\/Venta-naranja-Mercado.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2021\/12\/Venta-naranja-Mercado.jpg","width":1040,"height":692,"caption":"Foto: Agencia IP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/03\/16\/el-95-de-los-productos-frutihorticolas-se-importan-e-inicia-paulatinamente-la-siembra-de-verdeos-en-el-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Inicia siembra de verdeos en el pa\u00eds mientras se importa el 95% de los productos frutihort\u00edcolas"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/791af27a9219bdbf9064abb776bb41c2","name":"Noelia Ferreira","sameAs":["http:\/\/www.ip.gov.py"],"url":"https:\/\/www.ip.gov.py\/ip\/author\/nferreira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/408106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=408106"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/408106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/397634"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=408106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=408106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=408106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}