{"id":434165,"date":"2022-10-11T06:30:58","date_gmt":"2022-10-11T09:30:58","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=434165"},"modified":"2022-10-11T07:00:39","modified_gmt":"2022-10-11T10:00:39","slug":"consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/","title":{"rendered":"Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Asunci\u00f3n, Agencia IP.- <\/em><\/strong>Con la finalidad de ser incluidos en la agenda pol\u00edtica, bajo propuestas puntuales de acci\u00f3n por parte de las y los candidatos, el Consejo Joven del Fondo de Poblaci\u00f3n de las Naciones Unidas (Unfpa) elabor\u00f3 25 compromisos con la adolescencia y la juventud, en la que se destacan dos, \u201cAprovechar el bono demogr\u00e1fico para un desarrollo equitativo\u201d y \u201cgarantizar el acceso universal a la educaci\u00f3n\u201d.<!--more--><\/p>\n<p style=\"text-align: justify;\">\u00c9sta acci\u00f3n, se realiza en el contexto en que un importante n\u00famero de j\u00f3venes, se convertir\u00e1n en nuevos votantes en las pr\u00f3ximas elecciones, por lo que genera un clima ideal, para que las pr\u00f3ximas autoridades ratifiquen su compromiso con la juventud, bajo la premisa de estos 25 puntos.<\/p>\n<p style=\"text-align: justify;\">Es importante tener en cuenta que el bono demogr\u00e1fico del pa\u00eds sigue siendo una ventaja, si se invierte en pol\u00edticas p\u00fablicas que den mejores oportunidades a quienes se encuentran en dicha franja etaria.<\/p>\n<p style=\"text-align: justify;\">El Consejo Consultivo es una iniciativa del Fondo de Poblaci\u00f3n de las Naciones Unidas (Unfpa) que promueve la participaci\u00f3n protag\u00f3nica de adolescentes y j\u00f3venes en el an\u00e1lisis, debate y definici\u00f3n de abordajes sobre los temas que afectan a su desarrollo.<\/p>\n<p style=\"text-align: justify;\">Estos 25 compromisos se enfocan en diferentes \u00e1mbitos como: inversi\u00f3n, protecci\u00f3n, educaci\u00f3n, salud, empleo; cultura, recreaci\u00f3n y participaci\u00f3n; y tierra, vivienda y transporte.<\/p>\n<p style=\"text-align: justify;\">Actualmente, los j\u00f3venes representan al 27% de la poblaci\u00f3n total de Paraguay, y m\u00e1s que nunca, es importante brindar atenci\u00f3n al sector y promover su desarrollo integral, con el acompa\u00f1amiento de pol\u00edticas p\u00fablicas en diferentes aspectos que potencien la representatividad y garanticen el acceso a derechos.<\/p>\n<p style=\"text-align: justify;\">\u201cCreemos que las y los candidatos del Ejecutivo y Legislativo deber\u00edan de abordar las distintas problem\u00e1ticas de las y los j\u00f3venes y adolescentes a trav\u00e9s de pol\u00edticas p\u00fablicas acordes a las necesidades actuales, y poniendo \u00e9nfasis en el desarrollo que buscamos lograr como pa\u00eds\u201d, comenta Gonzalo Recalde, integrante del Consejo del Unfpa.<\/p>\n<p style=\"text-align: justify;\">\u201cPosterior a las elecciones, seguiremos a disposici\u00f3n y en contacto para revisar cada uno de los puntos, desde el Consejo, con el respaldo y acompa\u00f1amiento t\u00e9cnico del equipo del Unfpa en Paraguay\u201d, asegura y finaliza Recalde.<\/p>\n<p style=\"text-align: justify;\">La lista de los 25 compromisos est\u00e1n disponibles en <a href=\"http:\/\/bit.ly\/25CompromisosUNFPA\" target=\"_blank\" rel=\"noopener\"><strong>http:\/\/bit.ly\/25CompromisosUNFPA<\/strong><\/a>, y los mismos buscan ser un insumo para la ciudadan\u00eda y candidatos del ejecutivo y legislativo, para abordar propuestas y acciones para los pr\u00f3ximos a\u00f1os.<\/p>\n<h5 style=\"text-align: justify;\"><strong>Qu\u00e9 es el Consejo Joven del Unfpa?<\/strong><\/h5>\n<p style=\"text-align: justify;\">El Consejo Consultivo Adolescente y Joven es una iniciativa del Fondo de Poblaci\u00f3n de las Naciones Unidas (Unfpa) que promueve la participaci\u00f3n protag\u00f3nica de adolescentes y j\u00f3venes en el an\u00e1lisis, debate y definici\u00f3n de abordajes sobre los temas que afectan a su desarrollo.<\/p>\n<p style=\"text-align: justify;\">El objetivo de este grupo aut\u00f3nomo es recoger ideas, revisar propuestas, delinear estrategias, establecer metas y socializar la implementaci\u00f3n y los resultados en torno al aprovechamiento del bono demogr\u00e1fico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Agencia IP.- Con la finalidad de ser incluidos en la agenda pol\u00edtica, bajo propuestas puntuales de acci\u00f3n por parte de las y los candidatos, el Consejo Joven del Fondo de Poblaci\u00f3n de las Naciones Unidas (Unfpa) elabor\u00f3 25 compromisos con la adolescencia y la juventud, en la que se destacan dos, \u201cAprovechar el bono [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":434166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[11642,13671,1680,2613,10890,142,263,2602,2924],"class_list":{"0":"post-434165","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacionales","8":"tag-11642","9":"tag-13671","10":"tag-adolescentes","11":"tag-compromisos","12":"tag-consejo","13":"tag-gobierno","14":"tag-jovenes","15":"tag-juventud","16":"tag-unfpa"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023 - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023 - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Agencia IP.- Con la finalidad de ser incluidos en la agenda pol\u00edtica, bajo propuestas puntuales de acci\u00f3n por parte de las y los candidatos, el Consejo Joven del Fondo de Poblaci\u00f3n de las Naciones Unidas (Unfpa) elabor\u00f3 25 compromisos con la adolescencia y la juventud, en la que se destacan dos, \u201cAprovechar el bono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-11T09:30:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-11T10:00:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/10\/compromisos-jovenes-upfa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julio Davalos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julio Davalos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/\"},\"author\":{\"name\":\"Julio Davalos\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/eca17efa564153e0e4f59d8dfde23d1f\"},\"headline\":\"Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023\",\"datePublished\":\"2022-10-11T09:30:58+00:00\",\"dateModified\":\"2022-10-11T10:00:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/\"},\"wordCount\":526,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/compromisos-jovenes-upfa.jpg\",\"keywords\":[\"2023\",\"25\",\"Adolescentes\",\"Compromisos\",\"Consejo\",\"Gobierno\",\"J\u00f3venes\",\"Juventud\",\"UNFPA\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/\",\"name\":\"Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023 - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/compromisos-jovenes-upfa.jpg\",\"datePublished\":\"2022-10-11T09:30:58+00:00\",\"dateModified\":\"2022-10-11T10:00:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/compromisos-jovenes-upfa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/compromisos-jovenes-upfa.jpg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2022\\\/10\\\/11\\\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Agencia-IP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Agencia-IP.jpg\",\"width\":150,\"height\":150,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/eca17efa564153e0e4f59d8dfde23d1f\",\"name\":\"Julio Davalos\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/jdavalos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023 - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023 - .::Agencia IP::.","og_description":"Asunci\u00f3n, Agencia IP.- Con la finalidad de ser incluidos en la agenda pol\u00edtica, bajo propuestas puntuales de acci\u00f3n por parte de las y los candidatos, el Consejo Joven del Fondo de Poblaci\u00f3n de las Naciones Unidas (Unfpa) elabor\u00f3 25 compromisos con la adolescencia y la juventud, en la que se destacan dos, \u201cAprovechar el bono [&hellip;]","og_url":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2022-10-11T09:30:58+00:00","article_modified_time":"2022-10-11T10:00:39+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/10\/compromisos-jovenes-upfa.jpg","type":"image\/jpeg"}],"author":"Julio Davalos","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Julio Davalos","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/"},"author":{"name":"Julio Davalos","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/eca17efa564153e0e4f59d8dfde23d1f"},"headline":"Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023","datePublished":"2022-10-11T09:30:58+00:00","dateModified":"2022-10-11T10:00:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/"},"wordCount":526,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/10\/compromisos-jovenes-upfa.jpg","keywords":["2023","25","Adolescentes","Compromisos","Consejo","Gobierno","J\u00f3venes","Juventud","UNFPA"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/","url":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/","name":"Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023 - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/10\/compromisos-jovenes-upfa.jpg","datePublished":"2022-10-11T09:30:58+00:00","dateModified":"2022-10-11T10:00:39+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/10\/compromisos-jovenes-upfa.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2022\/10\/compromisos-jovenes-upfa.jpg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2022\/10\/11\/consejo-joven-del-unfpa-elabora-25-compromisos-con-la-adolescencia-y-juventud-para-el-gobierno-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Elaboran 25 compromisos con la adolescencia y juventud para el Gobierno 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2018\/01\/Agencia-IP.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2018\/01\/Agencia-IP.jpg","width":150,"height":150,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/eca17efa564153e0e4f59d8dfde23d1f","name":"Julio Davalos","url":"https:\/\/www.ip.gov.py\/ip\/author\/jdavalos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/434165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=434165"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/434165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/434166"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=434165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=434165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=434165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}