{"id":446174,"date":"2023-02-05T10:52:18","date_gmt":"2023-02-05T13:52:18","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=446174"},"modified":"2023-02-05T10:53:11","modified_gmt":"2023-02-05T13:53:11","slug":"el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/","title":{"rendered":"El Papa llama a \u00abdeponer las armas\u00bb al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Yuba.-<\/strong> <\/em>El papa Francisco hizo hoy un llamado a \u00abdeponer las armas\u00bb durante una misa al aire libre en Juba, la capital de Sud\u00e1n del Sur, que marc\u00f3 el final de su visita a dos pa\u00edses africanos desgarrados por la violencia y la miseria.<!--more--><\/p>\n<p style=\"text-align: justify;\">Francisco parti\u00f3 de Juba hacia el mediod\u00eda en el avi\u00f3n que lo llevaba de regreso al Vaticano, junto con los jefes de las iglesias de Inglaterra y Escocia, representantes de las otras dos confesiones cristianas de Sud\u00e1n del Sur con los que llev\u00f3 a cabo la visita.<\/p>\n<p style=\"text-align: justify;\">A lo largo de su visita de 48 horas, que sigui\u00f3 a otra a Rep\u00fablica Democr\u00e1tica del Congo, el pont\u00edfice hizo repetidas exhortaciones a la paz en Sud\u00e1n del Sur, de mayor\u00eda cristiana y 12 millones de habitantes.<\/p>\n<p style=\"text-align: justify;\">El pa\u00eds se vio inmerso entre 2013 y 2018 en una guerra civil entre los partidarios de los dos l\u00edderes rivales, Salva Kiir y Riek Machar, que dej\u00f3 380.000 muertos y millones de desplazados internos.<\/p>\n<p style=\"text-align: justify;\">\u00abDepongamos las armas del odio y de la venganza (&#8230;) superemos las antipat\u00edas y aversiones que, con el tiempo, se han vuelto cr\u00f3nicas y amenazan con contraponer las tribus y las etnias\u00bb dijo el Papa en la misa ante unos 70.000 fieles.<\/p>\n<p style=\"text-align: justify;\">Antes de la misa, Francisco, de 86 a\u00f1os, salud\u00f3 y bendijo a la multitud durante un paseo en su papam\u00f3vil, al ritmo de los gritos de alegr\u00eda y las panderetas, inform\u00f3 la agencia de noticias AFP.<\/p>\n<p style=\"text-align: justify;\">A su paso, la multitud coreaba \u00ab\u00a1Bienvenido a Sud\u00e1n del Sur!\u00bb, ondeando banderas del Estado m\u00e1s joven del mundo y del Vaticano.<\/p>\n<p style=\"text-align: justify;\">Ayer, Francisco pidi\u00f3 una \u00abvida digna\u00bb para los desplazados internos de este pa\u00eds del este de \u00c1frica, sin salida al mar, que en diciembre llegaban a unos 2,2 millones, seg\u00fan la ONU.<\/p>\n<p style=\"text-align: justify;\">Apenas arrib\u00f3, el Papa llam\u00f3 a los pol\u00edticos a dar \u00abun nuevo impulso\u00bb a la paz y conden\u00f3 la corrupci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La ONU y la comunidad internacional acusan a los dirigentes sursudaneses de alimentar la violencia, reprimir las libertades pol\u00edticas y malversar fondos p\u00fablicos.<\/p>\n<p style=\"text-align: justify;\">Los ej\u00e9rcitos personales de Kiir y Machar tambi\u00e9n est\u00e1n acusados de cr\u00edmenes de guerra.<\/p>\n<p style=\"text-align: justify;\">A pesar del acuerdo de paz firmado en 2018 en el pa\u00eds que se independiz\u00f3 de Sud\u00e1n en 2011, la violencia contin\u00faa<\/p>\n<p style=\"text-align: justify;\">El jueves, v\u00edspera de la llegada del Papa, al menos 21 personas murieron en un robo de ganado en el sur.<\/p>\n<p style=\"text-align: justify;\">En 2019, Francisco recibi\u00f3 a los dos enemigos en el Vaticano y se arrodill\u00f3 para besarles los pies, rog\u00e1ndoles que hicieran las paces, un gesto que no fue seguido de avances concretos.<\/p>\n<p style=\"text-align: justify;\">Antes de Juba, Francisco realiz\u00f3 una visita de cuatro d\u00edas a Kinshasa, la capital de la Rep\u00fablica Democr\u00e1tica del Congo, donde conden\u00f3 las \u00abatroces crueldades\u00bb de los grupos armados.<\/p>\n<p style=\"text-align: justify;\">Esta visita es la n\u00famero 40 del Papa argentino en el extranjero desde su elecci\u00f3n en 2013, y la tercera al \u00c1frica subsahariana. T\u00e9lam<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yuba.- El papa Francisco hizo hoy un llamado a \u00abdeponer las armas\u00bb durante una misa al aire libre en Juba, la capital de Sud\u00e1n del Sur, que marc\u00f3 el final de su visita a dos pa\u00edses africanos desgarrados por la violencia y la miseria.<\/p>\n","protected":false},"author":23,"featured_media":446175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[5728,3451,2121,14593],"class_list":["post-446174","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales","tag-africa","tag-papa","tag-papa-francisco","tag-sudan-del-sur"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Papa llama a &quot;deponer las armas&quot; al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Papa llama a &quot;deponer las armas&quot; al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Yuba.- El papa Francisco hizo hoy un llamado a \u00abdeponer las armas\u00bb durante una misa al aire libre en Juba, la capital de Sud\u00e1n del Sur, que marc\u00f3 el final de su visita a dos pa\u00edses africanos desgarrados por la violencia y la miseria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-05T13:52:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-05T13:53:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/02\/Papa-Sudan-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noelia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noelia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/\"},\"author\":{\"name\":\"Noelia Ferreira\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/791af27a9219bdbf9064abb776bb41c2\"},\"headline\":\"El Papa llama a \u00abdeponer las armas\u00bb al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica\",\"datePublished\":\"2023-02-05T13:52:18+00:00\",\"dateModified\":\"2023-02-05T13:53:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/\"},\"wordCount\":529,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Papa-Sudan-scaled.jpg\",\"keywords\":[\"Africa\",\"Papa\",\"Papa Francisco\",\"Sudan del Sur\"],\"articleSection\":[\"Internacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/\",\"name\":\"El Papa llama a \\\"deponer las armas\\\" al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Papa-Sudan-scaled.jpg\",\"datePublished\":\"2023-02-05T13:52:18+00:00\",\"dateModified\":\"2023-02-05T13:53:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Papa-Sudan-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Papa-Sudan-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"El papa Francisco hizo hoy un llamado a \\\"deponer las armas\\\" durante una misa al aire libre en Juba, la capital de Sud\u00e1n del Sur,. Foto: T\u00e9lam\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/02\\\/05\\\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Papa llama a \u00abdeponer las armas\u00bb al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/791af27a9219bdbf9064abb776bb41c2\",\"name\":\"Noelia Ferreira\",\"sameAs\":[\"http:\\\/\\\/www.ip.gov.py\"],\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/nferreira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Papa llama a \"deponer las armas\" al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/","og_locale":"es_ES","og_type":"article","og_title":"El Papa llama a \"deponer las armas\" al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica - .::Agencia IP::.","og_description":"Yuba.- El papa Francisco hizo hoy un llamado a \u00abdeponer las armas\u00bb durante una misa al aire libre en Juba, la capital de Sud\u00e1n del Sur, que marc\u00f3 el final de su visita a dos pa\u00edses africanos desgarrados por la violencia y la miseria.","og_url":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2023-02-05T13:52:18+00:00","article_modified_time":"2023-02-05T13:53:11+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/02\/Papa-Sudan-scaled.jpg","type":"image\/jpeg"}],"author":"Noelia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Noelia Ferreira","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/"},"author":{"name":"Noelia Ferreira","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/791af27a9219bdbf9064abb776bb41c2"},"headline":"El Papa llama a \u00abdeponer las armas\u00bb al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica","datePublished":"2023-02-05T13:52:18+00:00","dateModified":"2023-02-05T13:53:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/"},"wordCount":529,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/02\/Papa-Sudan-scaled.jpg","keywords":["Africa","Papa","Papa Francisco","Sudan del Sur"],"articleSection":["Internacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/","url":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/","name":"El Papa llama a \"deponer las armas\" al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/02\/Papa-Sudan-scaled.jpg","datePublished":"2023-02-05T13:52:18+00:00","dateModified":"2023-02-05T13:53:11+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/02\/Papa-Sudan-scaled.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/02\/Papa-Sudan-scaled.jpg","width":2560,"height":1707,"caption":"El papa Francisco hizo hoy un llamado a \"deponer las armas\" durante una misa al aire libre en Juba, la capital de Sud\u00e1n del Sur,. Foto: T\u00e9lam"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2023\/02\/05\/el-papa-llama-a-deponer-las-armas-al-cierre-de-visita-a-sudan-del-sur-y-de-su-gira-por-africa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"El Papa llama a \u00abdeponer las armas\u00bb al cierre de visita a Sud\u00e1n del Sur y de su gira por \u00c1frica"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/791af27a9219bdbf9064abb776bb41c2","name":"Noelia Ferreira","sameAs":["http:\/\/www.ip.gov.py"],"url":"https:\/\/www.ip.gov.py\/ip\/author\/nferreira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/446174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=446174"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/446174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/446175"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=446174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=446174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=446174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}