{"id":458790,"date":"2023-06-06T09:35:03","date_gmt":"2023-06-06T13:35:03","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=458790"},"modified":"2023-06-06T09:38:36","modified_gmt":"2023-06-06T13:38:36","slug":"como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/","title":{"rendered":"Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Asunci\u00f3n, Agencia IP.-<\/strong> <\/em>Un total de 17 personas privadas de libertad de la Granja Penitenciaria Ko&#8217;e Pyahu de la localidad de Emboscada, realizan este martes, una jornada de limpieza ambiental en la Costanera de Asunci\u00f3n con el fin de fomentar la reinserci\u00f3n social a trav\u00e9s del servicio a la comunidad.<!--more--><\/p>\n<p style=\"text-align: justify;\">En la apertura del encuentro, el ministro de Justicia, Daniel Ben\u00edtez, refiri\u00f3 que la actividad forma parte de un proceso que busca dar oportunidad a las personas privadas de libertad que \u00abest\u00e1n condenadas, que trabajan y estudian que desean salir adelante siendo esta una muy buena oportunidad para que se involucren con la sociedad\u00bb, manifest\u00f3.<\/p>\n<p style=\"text-align: justify;\">Sobre el \u00faltimo punto sostuvo que \u00abla sociedad tiene temor a la gente que estuvo recluida en una penitenciaria, entonces lo que buscamos es familiarizar a la ciudadan\u00eda y que tengan en cuenta de que estas personas no le causar\u00e1n ning\u00fan da\u00f1o. Son personas que quieren otra oportunidad y nosotros debemos darle esa oportunidad\u00bb, reconoci\u00f3.<\/p>\n<p style=\"text-align: justify;\">Afirm\u00f3 que esta es la \u00faltima etapa que ellos deben pasar para obtener la libertad. \u00abAlgunos de ellos ya cuentan con salida transitoria, beneficios o redenciones, y estos trabajos comunitarios le va a sumar beneficios en su Juzgado de Ejecuci\u00f3n\u00bb, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">En cuanto a las internas del Buen Pastor manifest\u00f3 que actualmente cuentan con un proyecto con una empresa maquiladora que quiere contar con la mano de obra de las mujeres que se encuentran recluidas. \u00abEllas ya tuvieron su primera experiencia y ahora la empresa est\u00e1 pidiendo aumentar la producci\u00f3n\u00bb, refiri\u00f3.<\/p>\n<p style=\"text-align: justify;\">El titular de Justicia sostuvo que este tipo de opciones con las que se deben plantear a las personas privadas de libertad, ya que \u00ablo que m\u00e1s les afecta o perjudica es el ocio, estar sin tener una actividad hace que muchas veces se dediquen a cosas no productivas\u00bb, dijo finalmente en entrevista con Paraguay TV.<\/p>\n<p style=\"text-align: justify;\">Esta iniciativa forma parte del programa \u00abTransformando mi ciudad: Servicio que nos une, trabajo que restaura\u00bb que es impulsado por el Ministerio de Justicia y cuenta con el apoyo de la Municipalidad de Asunci\u00f3n. El mismo busca no solo contribuir al bienestar del medio ambiente, sino tambi\u00e9n brindar a las personas privadas de libertad la oportunidad de participar activamente en la sociedad y demostrar su capacidad para generar un impacto positivo en la comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Agencia IP.- Un total de 17 personas privadas de libertad de la Granja Penitenciaria Ko&#8217;e Pyahu de la localidad de Emboscada, realizan este martes, una jornada de limpieza ambiental en la Costanera de Asunci\u00f3n con el fin de fomentar la reinserci\u00f3n social a trav\u00e9s del servicio a la comunidad.<\/p>\n","protected":false},"author":23,"featured_media":458794,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[924,1344,15279,406],"class_list":["post-458790","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-costanera-de-asuncion","tag-internos","tag-jornada-de-limpieza","tag-ministerio-de-justicia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Agencia IP.- Un total de 17 personas privadas de libertad de la Granja Penitenciaria Ko&#8217;e Pyahu de la localidad de Emboscada, realizan este martes, una jornada de limpieza ambiental en la Costanera de Asunci\u00f3n con el fin de fomentar la reinserci\u00f3n social a trav\u00e9s del servicio a la comunidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-06T13:35:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T13:38:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/06\/Koe-Pyahu-Penitenciaria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1064\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noelia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noelia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/\"},\"author\":{\"name\":\"Noelia Ferreira\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/791af27a9219bdbf9064abb776bb41c2\"},\"headline\":\"Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n\",\"datePublished\":\"2023-06-06T13:35:03+00:00\",\"dateModified\":\"2023-06-06T13:38:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/\"},\"wordCount\":414,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Koe-Pyahu-Penitenciaria.jpg\",\"keywords\":[\"Costanera de Asunci\u00f3n\",\"Internos\",\"jornada de limpieza\",\"Ministerio de Justicia\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/\",\"name\":\"Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Koe-Pyahu-Penitenciaria.jpg\",\"datePublished\":\"2023-06-06T13:35:03+00:00\",\"dateModified\":\"2023-06-06T13:38:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Koe-Pyahu-Penitenciaria.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Koe-Pyahu-Penitenciaria.jpg\",\"width\":1600,\"height\":1064,\"caption\":\"Foto: Agencia IP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2023\\\/06\\\/06\\\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/791af27a9219bdbf9064abb776bb41c2\",\"name\":\"Noelia Ferreira\",\"sameAs\":[\"http:\\\/\\\/www.ip.gov.py\"],\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/nferreira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/","og_locale":"es_ES","og_type":"article","og_title":"Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n - .::Agencia IP::.","og_description":"Asunci\u00f3n, Agencia IP.- Un total de 17 personas privadas de libertad de la Granja Penitenciaria Ko&#8217;e Pyahu de la localidad de Emboscada, realizan este martes, una jornada de limpieza ambiental en la Costanera de Asunci\u00f3n con el fin de fomentar la reinserci\u00f3n social a trav\u00e9s del servicio a la comunidad.","og_url":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2023-06-06T13:35:03+00:00","article_modified_time":"2023-06-06T13:38:36+00:00","og_image":[{"width":1600,"height":1064,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/06\/Koe-Pyahu-Penitenciaria.jpg","type":"image\/jpeg"}],"author":"Noelia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Noelia Ferreira","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/"},"author":{"name":"Noelia Ferreira","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/791af27a9219bdbf9064abb776bb41c2"},"headline":"Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n","datePublished":"2023-06-06T13:35:03+00:00","dateModified":"2023-06-06T13:38:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/"},"wordCount":414,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/06\/Koe-Pyahu-Penitenciaria.jpg","keywords":["Costanera de Asunci\u00f3n","Internos","jornada de limpieza","Ministerio de Justicia"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/","url":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/","name":"Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/06\/Koe-Pyahu-Penitenciaria.jpg","datePublished":"2023-06-06T13:35:03+00:00","dateModified":"2023-06-06T13:38:36+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/06\/Koe-Pyahu-Penitenciaria.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2023\/06\/Koe-Pyahu-Penitenciaria.jpg","width":1600,"height":1064,"caption":"Foto: Agencia IP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2023\/06\/06\/como-parte-de-su-reinsersion-social-internos-realizan-jornada-de-limpieza-en-costanera-de-asuncion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Como parte de su reinsersi\u00f3n social, internos realizan jornada de limpieza en Costanera de Asunci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/791af27a9219bdbf9064abb776bb41c2","name":"Noelia Ferreira","sameAs":["http:\/\/www.ip.gov.py"],"url":"https:\/\/www.ip.gov.py\/ip\/author\/nferreira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/458790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=458790"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/458790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/458794"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=458790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=458790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=458790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}