{"id":484330,"date":"2024-01-23T17:57:33","date_gmt":"2024-01-23T20:57:33","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=484330"},"modified":"2024-01-23T17:57:33","modified_gmt":"2024-01-23T20:57:33","slug":"construyen-14-usf-en-el-departamento-de-amambay","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/","title":{"rendered":"Construyen 14 USF en el departamento de Amambay"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Asunci\u00f3n, Agencia IP.- <\/strong><\/em>En el departamento de Amambay avanzan las obras de 14 Unidades de Salud Familiar (USF) nuevas, incluida una en territorio de la comunidad ind\u00edgena Ybypyte.<!--more--><\/p>\n<p style=\"text-align: justify;\">Las USF permiten ampliar la cobertura de atenci\u00f3n primaria de la salud en las comunidades del departamento. Una vez culminadas se contar\u00e1n con 36 establecimientos para la promoci\u00f3n de la salud y prevenci\u00f3n de enfermedades.<\/p>\n<p style=\"text-align: justify;\">Diez USF se construyen en el distrito de Pedro Juan Caballero, y, por primera vez en el departamento, una se edifica en la comunidad ind\u00edgena Ybypyte, en el distrito de Cerro Cora. La misma abarcar\u00e1 en su \u00e1rea de influencia a ocho comunidades m\u00e1s, ampliando as\u00ed la asistencia a los pobladores.<\/p>\n<p style=\"text-align: justify;\">Las habilitaciones est\u00e1n previstas entre mayo y junio de este a\u00f1o. Las obras son financiadas por el Banco Mundial y ser\u00e1n equipadas y dotadas del recurso humano necesario por el Ministerio de Salud P\u00fablica, para asistir en medicina familiar, enfermer\u00eda y odontolog\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Agencia IP.- En el departamento de Amambay avanzan las obras de 14 Unidades de Salud Familiar (USF) nuevas, incluida una en territorio de la comunidad ind\u00edgena Ybypyte.<\/p>\n","protected":false},"author":22,"featured_media":484331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2987],"tags":[],"class_list":{"0":"post-484330","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-salud"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Construyen 14 USF en el departamento de Amambay - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Construyen 14 USF en el departamento de Amambay - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Agencia IP.- En el departamento de Amambay avanzan las obras de 14 Unidades de Salud Familiar (USF) nuevas, incluida una en territorio de la comunidad ind\u00edgena Ybypyte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T20:57:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/01\/construccion-usf-amambay.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"652\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alberto C\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alberto C\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/\"},\"author\":{\"name\":\"Alberto C\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/369fedd28420fad35e23b10a9df16fb8\"},\"headline\":\"Construyen 14 USF en el departamento de Amambay\",\"datePublished\":\"2024-01-23T20:57:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/\"},\"wordCount\":176,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/construccion-usf-amambay.jpg\",\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/\",\"name\":\"Construyen 14 USF en el departamento de Amambay - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/construccion-usf-amambay.jpg\",\"datePublished\":\"2024-01-23T20:57:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/construccion-usf-amambay.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/construccion-usf-amambay.jpg\",\"width\":870,\"height\":652,\"caption\":\"Foto MSPBS.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/01\\\/23\\\/construyen-14-usf-en-el-departamento-de-amambay\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Construyen 14 USF en el departamento de Amambay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Agencia-IP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Agencia-IP.jpg\",\"width\":150,\"height\":150,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/369fedd28420fad35e23b10a9df16fb8\",\"name\":\"Alberto C\",\"sameAs\":[\"https:\\\/\\\/www.ip.gov.py\"],\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/acelma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Construyen 14 USF en el departamento de Amambay - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/","og_locale":"es_ES","og_type":"article","og_title":"Construyen 14 USF en el departamento de Amambay - .::Agencia IP::.","og_description":"Asunci\u00f3n, Agencia IP.- En el departamento de Amambay avanzan las obras de 14 Unidades de Salud Familiar (USF) nuevas, incluida una en territorio de la comunidad ind\u00edgena Ybypyte.","og_url":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2024-01-23T20:57:33+00:00","og_image":[{"width":870,"height":652,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/01\/construccion-usf-amambay.jpg","type":"image\/jpeg"}],"author":"Alberto C","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Alberto C","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/"},"author":{"name":"Alberto C","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/369fedd28420fad35e23b10a9df16fb8"},"headline":"Construyen 14 USF en el departamento de Amambay","datePublished":"2024-01-23T20:57:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/"},"wordCount":176,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/01\/construccion-usf-amambay.jpg","articleSection":["Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/","url":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/","name":"Construyen 14 USF en el departamento de Amambay - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/01\/construccion-usf-amambay.jpg","datePublished":"2024-01-23T20:57:33+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/01\/construccion-usf-amambay.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/01\/construccion-usf-amambay.jpg","width":870,"height":652,"caption":"Foto MSPBS."},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/01\/23\/construyen-14-usf-en-el-departamento-de-amambay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Construyen 14 USF en el departamento de Amambay"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2018\/01\/Agencia-IP.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2018\/01\/Agencia-IP.jpg","width":150,"height":150,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/369fedd28420fad35e23b10a9df16fb8","name":"Alberto C","sameAs":["https:\/\/www.ip.gov.py"],"url":"https:\/\/www.ip.gov.py\/ip\/author\/acelma\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/484330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=484330"}],"version-history":[{"count":1,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/484330\/revisions"}],"predecessor-version":[{"id":484332,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/484330\/revisions\/484332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/484331"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=484330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=484330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=484330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}