{"id":485263,"date":"2024-02-02T12:32:46","date_gmt":"2024-02-02T15:32:46","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=485263"},"modified":"2024-02-04T09:09:17","modified_gmt":"2024-02-04T12:09:17","slug":"hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/","title":{"rendered":"\u00abHambre Cero\u00bb contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Asunci\u00f3n, Agencia IP.-<\/strong><\/em> Una alimentaci\u00f3n correcta y saludable en los ni\u00f1os, desde el \u00fatero materno, contribuye en su crecimiento corporal, desarrollo cognitivo, sus habilidades y en el relacionamiento social, que le permitir\u00e1 desenvolverse en el estudio y el trabajo para triunfar en la vida adulta. Aumenta el futuro en el Producto Interno Bruto (PIB) de un pa\u00eds; ah\u00ed radica la importancia del proyecto \u201cHambre Cero\u201d impulsado por el Gobierno del Paraguay, sostuvo el presidente de la Sociedad Paraguaya de Pediatr\u00eda, doctor Ernesto Weber.<!--more--><\/p>\n<p style=\"text-align: justify;\">La \u201cNutrici\u00f3n en la primera infancia\u201d, es de suma relevancia para lograr el crecimiento adecuado de los ni\u00f1os, desde los primeros a\u00f1os de vida, buscando erradicar la desnutrici\u00f3n infantil y el ausentismo escolar; por lo que varios pediatras de nuestro pa\u00eds, apoyan esta iniciativa gubernamental.<\/p>\n<p style=\"text-align: justify;\">El doctor Ernesto Weber, presidente de la Sociedad Paraguaya de Pediatr\u00eda, habl\u00f3 acerca de la importancia de la alimentaci\u00f3n correcta en los ni\u00f1os y dio varios consejos pr\u00e1cticos para su implementaci\u00f3n en la primera infancia durante una entrevista en el programa \u201cLa Ma\u00f1ana\u201d, que se emite por Unicanal.<\/p>\n<p style=\"text-align: justify;\">\u201cRealmente un tema apasionante sobre todo para los pediatras pero tambi\u00e9n para los padres, todos queremos lograr un futuro mejor para nuestros hijos y que nos superen en todo lo que nosotros llegamos a hacer&#8230; No solamente es importante la nutrici\u00f3n en el ni\u00f1o, sino que el Ministerio de Salud habla de los mil primeros d\u00edas, incluye los nueve meses de embarazo, entonces es muy importante que la persona que va a embarazarse est\u00e9 bien nutrida\u201d, asever\u00f3 el profesional.<\/p>\n<p style=\"text-align: justify;\">Lament\u00f3 que en nuestro pa\u00eds exista un c\u00edrculo vicioso, con madres adolescentes desnutridas, an\u00e9micas, y carencias de los nutrientes, que conlleva en el nacimiento precoz, reci\u00e9n nacidos con deficiencia, en hierro y bajo peso al nacer. Este hecho repercute en el desarrollo del infante, perjudicando el rendimiento escolar o el abandono de las escuelas.<\/p>\n<p style=\"text-align: justify;\">Un inconveniente m\u00e1s que se le a\u00f1ade al problema de desnutrici\u00f3n es la baja adherencia a la lactancia materna, con el consumo exclusivo de la leche materna del ni\u00f1o hasta los seis meses de vida.<\/p>\n<p style=\"text-align: justify;\">Sostuvo que \u201ceste proyecto es muy ambicioso, tiene demasiadas aristas que controlar\u201d, manifestando que desde la Sociedad de Pediatr\u00eda acompa\u00f1an al Gobierno Nacional, de manera a que la poblaci\u00f3n act\u00fae como veedora del proyecto \u201cHambre Cero\u201d para controlar que los ni\u00f1os reciban todos los nutrientes y la alimentaci\u00f3n que corresponde.<\/p>\n<h4 style=\"text-align: justify;\"><strong>M\u00e1s frutas y verduras<\/strong><\/h4>\n<p style=\"text-align: justify;\">Enfatiz\u00f3 que Paraguay es rico en producir alimentos y que la comida paraguaya es sana y nutritiva, por lo que los padres deben incluir lo que la tierra ofrece, con una dieta balanceada que incluya en un 50% frutas y verduras, 25% carnes y legumbres, y 25% hidrato de carbono como harinas, arroz y almid\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u201cHay estudios muy interesantes que hace Unicef, OPS el BID donde demostraron que pa\u00edses donde se cambi\u00f3 la dieta del ni\u00f1o a este tipo de una dieta m\u00e1s balanceada donde el 50% es vegetales, frutas, verduras y solamente un cuarto es carne, prote\u00ednas, poroto, lentejas toda la fuente de prote\u00edna y solamente un cuarto de esta porci\u00f3n de comida es hidrato de carbono, es un ni\u00f1o que tiene un desarrollo mucho mejor, no solamente en la parte pondoestatural, en estatura, el crecimiento del cuerpo sino en el desarrollo de ese ni\u00f1o y no solo en el desarrollo cognitivo de lo que es habilidades, destrezas, de saber hablar, moverse, de andar en bicicleta; sino tambi\u00e9n en el desarrollo afectivo del ni\u00f1o que es s\u00faper importante, la parte de empat\u00eda, responsabilidad social, de relacionamiento con otros ni\u00f1os\u201d, recalc\u00f3.<\/p>\n<p style=\"text-align: justify;\">Otro de los aspectos destacados por el doctor Weber es que un ni\u00f1o bien nutrido, de un 4% aumenta a un 11% en el futuro en el Producto Interno Bruto de un pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">\u201cUn ni\u00f1o bien nutrido en la edad de lactante, la edad preescolar y escolar, cuando termina el colegio tiene m\u00e1s posibilidades de ser una persona exitosa, de conseguir trabajo, de triunfar en la vida\u00a0 y creo que los padres en general es lo que queremos para nuestros hijos\u201d, afirm\u00f3.<\/p>\n<h4 style=\"text-align: justify;\"><strong>La casa y la escuela deben ense\u00f1ar buenos h\u00e1bitos alimenticios<\/strong><\/h4>\n<p style=\"text-align: justify;\">En otro orden, el pediatra manifest\u00f3 que tanto la familia en la casa, como los docentes en las escuelas deben ense\u00f1ar a los ni\u00f1os buenos h\u00e1bitos alimenticios con la correcta manipulaci\u00f3n y conservaci\u00f3n de los alimentos; priorizando una dieta balanceada.<\/p>\n<p style=\"text-align: justify;\">\u201cOtro problema es que los ni\u00f1os no reciben educaci\u00f3n en alimentaci\u00f3n, muchas veces los padres j\u00f3venes creen que es mejor darles un alimento que viene del extranjero, que es costoso como el kiwi o ar\u00e1ndanos; sin embargo tenemos mangos, pomelos que se caen y se pudren o el mam\u00f3n que crece en todos los patios. Entonces hay muchos alimentos en Paraguay, en realidad somos un pa\u00eds bendecido en alimentos, hay muchos alimentos, y es un tema importante que los ni\u00f1os no aprenden en la escuela tambi\u00e9n h\u00e1bitos de manipulaci\u00f3n de estos alimentos, entonces saber preparar, por un lado, saber conservar y cuales usar para qu\u00e9 cosas\u201d, se\u00f1al\u00f3.<\/p>\n<p style=\"text-align: justify;\">\u201cEs importante decirle a los padres que no todo lo que viene de afuera es saludable y es bueno, yo hablo con los pacientes si ya comi\u00f3 vor\u00ed, soyo, tortilla, porque la otra est\u00e1 en la pizza, la hamburguesa, papas fritas, alfajores. Hay tantos alimentos nuestros t\u00edpicos paraguayos que son nutritivos, el ni\u00f1o tiene que limitar su porci\u00f3n, con los ni\u00f1os hay que supervisar y esto es un desaf\u00edo para este proyecto, conseguir en la calidad de los alimentos\u201d, acot\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Agencia IP.- Una alimentaci\u00f3n correcta y saludable en los ni\u00f1os, desde el \u00fatero materno, contribuye en su crecimiento corporal, desarrollo cognitivo, sus habilidades y en el relacionamiento social, que le permitir\u00e1 desenvolverse en el estudio y el trabajo para triunfar en la vida adulta. Aumenta el futuro en el Producto Interno Bruto (PIB) de [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":56187,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2987],"tags":[14205,9209,2220,7541],"class_list":["post-485263","post","type-post","status-publish","format-standard","has-post-thumbnail","category-salud","tag-alimentacion-saludable","tag-hambre-cero","tag-mspybs","tag-sociedad-paraguaya-de-pediatria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Hambre Cero&quot; contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Hambre Cero&quot; contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Agencia IP.- Una alimentaci\u00f3n correcta y saludable en los ni\u00f1os, desde el \u00fatero materno, contribuye en su crecimiento corporal, desarrollo cognitivo, sus habilidades y en el relacionamiento social, que le permitir\u00e1 desenvolverse en el estudio y el trabajo para triunfar en la vida adulta. Aumenta el futuro en el Producto Interno Bruto (PIB) de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-02T15:32:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-04T12:09:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/10\/Comida-Ninos-ALIMENTOS-COMEDOR-BA\u00d1ADO1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"623\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jzelada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jzelada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/\"},\"author\":{\"name\":\"jzelada\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/b0f4c235f0f0d7a0985bbb33c6a7941e\"},\"headline\":\"\u00abHambre Cero\u00bb contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra\",\"datePublished\":\"2024-02-02T15:32:46+00:00\",\"dateModified\":\"2024-02-04T12:09:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/\"},\"wordCount\":995,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Comida-Ninos-ALIMENTOS-COMEDOR-BA\u00d1ADO1.jpg\",\"keywords\":[\"alimentaci\u00f3n saludable\",\"hambre cero\",\"MspyBs\",\"Sociedad Paraguaya de Pediatr\u00eda\"],\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/\",\"name\":\"\\\"Hambre Cero\\\" contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Comida-Ninos-ALIMENTOS-COMEDOR-BA\u00d1ADO1.jpg\",\"datePublished\":\"2024-02-02T15:32:46+00:00\",\"dateModified\":\"2024-02-04T12:09:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Comida-Ninos-ALIMENTOS-COMEDOR-BA\u00d1ADO1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Comida-Ninos-ALIMENTOS-COMEDOR-BA\u00d1ADO1.jpg\",\"width\":1000,\"height\":623,\"caption\":\"Pediatra celebra el proyecto Hambre cero para reducir la desnutrici\u00f3n infantil la deserci\u00f3n escolar. Foto gentileza.-\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/02\\\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abHambre Cero\u00bb contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/b0f4c235f0f0d7a0985bbb33c6a7941e\",\"name\":\"jzelada\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/jzelada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Hambre Cero\" contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/","og_locale":"es_ES","og_type":"article","og_title":"\"Hambre Cero\" contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra - .::Agencia IP::.","og_description":"Asunci\u00f3n, Agencia IP.- Una alimentaci\u00f3n correcta y saludable en los ni\u00f1os, desde el \u00fatero materno, contribuye en su crecimiento corporal, desarrollo cognitivo, sus habilidades y en el relacionamiento social, que le permitir\u00e1 desenvolverse en el estudio y el trabajo para triunfar en la vida adulta. Aumenta el futuro en el Producto Interno Bruto (PIB) de [&hellip;]","og_url":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2024-02-02T15:32:46+00:00","article_modified_time":"2024-02-04T12:09:17+00:00","og_image":[{"width":1000,"height":623,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/10\/Comida-Ninos-ALIMENTOS-COMEDOR-BA\u00d1ADO1.jpg","type":"image\/jpeg"}],"author":"jzelada","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"jzelada","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/"},"author":{"name":"jzelada","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/b0f4c235f0f0d7a0985bbb33c6a7941e"},"headline":"\u00abHambre Cero\u00bb contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra","datePublished":"2024-02-02T15:32:46+00:00","dateModified":"2024-02-04T12:09:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/"},"wordCount":995,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/10\/Comida-Ninos-ALIMENTOS-COMEDOR-BA\u00d1ADO1.jpg","keywords":["alimentaci\u00f3n saludable","hambre cero","MspyBs","Sociedad Paraguaya de Pediatr\u00eda"],"articleSection":["Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/","url":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/","name":"\"Hambre Cero\" contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/10\/Comida-Ninos-ALIMENTOS-COMEDOR-BA\u00d1ADO1.jpg","datePublished":"2024-02-02T15:32:46+00:00","dateModified":"2024-02-04T12:09:17+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/10\/Comida-Ninos-ALIMENTOS-COMEDOR-BA\u00d1ADO1.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/10\/Comida-Ninos-ALIMENTOS-COMEDOR-BA\u00d1ADO1.jpg","width":1000,"height":623,"caption":"Pediatra celebra el proyecto Hambre cero para reducir la desnutrici\u00f3n infantil la deserci\u00f3n escolar. Foto gentileza.-"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/02\/hambre-cero-contribuira-a-formar-ciudadanos-exitosos-y-elevar-el-pib-del-paraguay-afirmo-pediatra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"\u00abHambre Cero\u00bb contribuir\u00e1 a formar ciudadanos exitosos y elevar el PIB del Paraguay, afirm\u00f3 pediatra"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/b0f4c235f0f0d7a0985bbb33c6a7941e","name":"jzelada","url":"https:\/\/www.ip.gov.py\/ip\/author\/jzelada\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/485263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=485263"}],"version-history":[{"count":2,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/485263\/revisions"}],"predecessor-version":[{"id":485266,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/485263\/revisions\/485266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/56187"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=485263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=485263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=485263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}