{"id":487959,"date":"2024-02-23T08:06:48","date_gmt":"2024-02-23T11:06:48","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=487959"},"modified":"2024-02-23T08:06:48","modified_gmt":"2024-02-23T11:06:48","slug":"con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/","title":{"rendered":"Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Quito.-<\/strong><\/em>El goleador paraguayo Alex Arce disfrut\u00f3 de un debut so\u00f1ado al convertir el gol del triunfo por 1-0 de Liga de Quito sobre el Fluminense de Brasil, en el partido de ida por el t\u00edtulo de la Recopa Sudamericana disputado este jueves en la capital ecuatoriana.<!--more--><\/p>\n<p style=\"text-align: justify;\">Arce, que lleg\u00f3 reci\u00e9n esta semana a Quito para vincularse a su nuevo equipo, ingres\u00f3 al minuto 56 y en el 91 convirti\u00f3 el gol que puso en ventaja a Liga, que el pr\u00f3ximo jueves visitar\u00e1 al Fluminense en el partido final de la presente edici\u00f3n del certamen internacional.<\/p>\n<p style=\"text-align: justify;\">Cuando m\u00e1s cerca estuvo Fluminense de llevarse el empate, el Rey de Copas de Ecuador logr\u00f3 el triunfo para desatar la alegr\u00eda de unos 35.000 aficionados que llegaron a su estadio. El fantasma de las finales perdidas ante Liga Deportiva Universitaria qued\u00f3 rondando entre los del club brasile\u00f1os, que ya hab\u00edan perdido ante este mismo rival las finales de la Copa Libertadores de 2008 y de la Copa Sudamericana de 2009.<\/p>\n<p style=\"text-align: justify;\">El toque de bal\u00f3n en espacios reducidos, los movimientos precisos y sincronizados en su propia zona, la respuesta oportuna del portero Fabio y la falta de punter\u00eda de los atacantes locales le permitieron a Fluminense terminar el primer tiempo sin recibir goles.<\/p>\n<p style=\"text-align: justify;\">A pesar de jugar encerrado en su zona, el equipo que dirige Fernando Diniz fabric\u00f3 dos llegadas con posibilidad de gol, que logr\u00f3 ganar por experiencia el portero Alexander Dom\u00ednguez. El guardameta ecuatoriano oblig\u00f3 a Cano a apurarse en el remate y a chocarse con \u00e9l, el VAR alert\u00f3 al \u00e1rbitro colombiano Andr\u00e9s Rojas que, tras observar la acci\u00f3n, descart\u00f3 un posible penal. Dom\u00ednguez tambi\u00e9n cerr\u00f3 el arco al remate desde corta distancia del colombiano Jhon Arias.<\/p>\n<p style=\"text-align: justify;\">Liga sali\u00f3 al descanso masticando impotencia por la falta de punter\u00eda de sus volantes y atacantes que, despu\u00e9s de bombardear con ocho remates desde fuera del \u00e1rea, no lograron vulnerar la valla brasile\u00f1a. La presi\u00f3n del local oblig\u00f3 a un error defensivo, pero el portero Fabio rechaz\u00f3 el bal\u00f3n desde la l\u00ednea de sentencia, al minuto 4.<\/p>\n<p style=\"text-align: justify;\">Luego Oscar Zambrano prob\u00f3 con dos tiros sin romper el arco contrario, el argentino Lucas Piovi remat\u00f3 apenas desviado y Sebasti\u00e1n Gonz\u00e1lez disfrut\u00f3 de tres ocasiones, una salvada por Fabio, otra con disparo junto al arco y un rebote afuera.<\/p>\n<p style=\"text-align: justify;\">Sobre el final del primer tiempo, Guga rechaz\u00f3 el bal\u00f3n en lo que pudo ser un gol ol\u00edmpico de Piovi. Desde la reanudaci\u00f3n del partido, Fluminense se encerr\u00f3 m\u00e1s en su propia zona para tratar de reducir los espacios al local. El debutante paraguayo Alex Arce y el venezolano Jan Hurtado tampoco lograron rematar con direcci\u00f3n al arco, en otro ataque fallido.<\/p>\n<p style=\"text-align: justify;\">En un nuevo intento de Liga de Quito, el bal\u00f3n se desvi\u00f3 en la pierna de Andr\u00e9 para salvar una vez m\u00e1s a Fluminense, ante el remate del venezolano Hurtado. El disparo de Lima, que reemplaz\u00f3 al argentino Cano, se estrell\u00f3 en el travesa\u00f1o, en uno de los pocos ataques del Flu en el segundo tiempo.<\/p>\n<p style=\"text-align: justify;\">El control de la acciones, frenar al m\u00e1ximo cada vez que deb\u00edan reanudar el juego en los saques de arco, en los tiros libres o los saques laterales, fue otro de los recursos que utiliz\u00f3 Fluminense para desesperar al rival, que reclam\u00f3 por cada interrupci\u00f3n al \u00e1rbitro Rojas. Jos\u00e9 Quintero tambi\u00e9n busc\u00f3 el gol con remate que logr\u00f3 rechazar Fabio.<\/p>\n<p style=\"text-align: justify;\">Hasta que sobre el final del partido, el paraguayo Arce logr\u00f3 romper el cerrojo brasile\u00f1o, con un leve toque de bal\u00f3n con el pie derecho; el \u00e1rbitro Rojas recurri\u00f3 al VAR y corrobor\u00f3 que el debutante paraguayo s\u00ed estaba habilitado en la acci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La revancha se llevar\u00e1 a cabo el pr\u00f3ximo jueves en el estadio Maracan\u00e1 de R\u00edo de Janeiro.Infobae.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quito.-El goleador paraguayo Alex Arce disfrut\u00f3 de un debut so\u00f1ado al convertir el gol del triunfo por 1-0 de Liga de Quito sobre el Fluminense de Brasil, en el partido de ida por el t\u00edtulo de la Recopa Sudamericana disputado este jueves en la capital ecuatoriana.<\/p>\n","protected":false},"author":11,"featured_media":487961,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[15785,2623,7666,418,5947,14757],"class_list":["post-487959","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes","tag-conmebol-liga-de-quito","tag-final","tag-fluminense","tag-futbol","tag-ida","tag-recopa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Quito.-El goleador paraguayo Alex Arce disfrut\u00f3 de un debut so\u00f1ado al convertir el gol del triunfo por 1-0 de Liga de Quito sobre el Fluminense de Brasil, en el partido de ida por el t\u00edtulo de la Recopa Sudamericana disputado este jueves en la capital ecuatoriana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-23T11:06:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/02\/Alex-Arce.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vrios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vrios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/\"},\"author\":{\"name\":\"vrios\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/fa3668852e893cb0423795330f919039\"},\"headline\":\"Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana\",\"datePublished\":\"2024-02-23T11:06:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/\"},\"wordCount\":675,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Alex-Arce.jpg\",\"keywords\":[\"Conmebol. Liga de Quito\",\"Final\",\"Fluminense\",\"F\u00fatbol\",\"Ida\",\"Recopa\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/\",\"name\":\"Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Alex-Arce.jpg\",\"datePublished\":\"2024-02-23T11:06:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Alex-Arce.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Alex-Arce.jpg\",\"width\":840,\"height\":540,\"caption\":\"El Nacional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2024\\\/02\\\/23\\\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/fa3668852e893cb0423795330f919039\",\"name\":\"vrios\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/vrios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/","og_locale":"es_ES","og_type":"article","og_title":"Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana - .::Agencia IP::.","og_description":"Quito.-El goleador paraguayo Alex Arce disfrut\u00f3 de un debut so\u00f1ado al convertir el gol del triunfo por 1-0 de Liga de Quito sobre el Fluminense de Brasil, en el partido de ida por el t\u00edtulo de la Recopa Sudamericana disputado este jueves en la capital ecuatoriana.","og_url":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2024-02-23T11:06:48+00:00","og_image":[{"width":840,"height":540,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/02\/Alex-Arce.jpg","type":"image\/jpeg"}],"author":"vrios","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"vrios","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/"},"author":{"name":"vrios","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/fa3668852e893cb0423795330f919039"},"headline":"Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana","datePublished":"2024-02-23T11:06:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/"},"wordCount":675,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/02\/Alex-Arce.jpg","keywords":["Conmebol. Liga de Quito","Final","Fluminense","F\u00fatbol","Ida","Recopa"],"articleSection":["Deportes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/","url":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/","name":"Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/02\/Alex-Arce.jpg","datePublished":"2024-02-23T11:06:48+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/02\/Alex-Arce.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/02\/Alex-Arce.jpg","width":840,"height":540,"caption":"El Nacional"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2024\/02\/23\/con-gol-del-paraguayo-alex-arce-liga-de-quito-gana-la-primera-final-de-la-recopa-sudamericana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Con gol del Paraguayo Alex Arce , Liga de Quito gana la primera final de la Recopa Sudamericana"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/fa3668852e893cb0423795330f919039","name":"vrios","url":"https:\/\/www.ip.gov.py\/ip\/author\/vrios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/487959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=487959"}],"version-history":[{"count":1,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/487959\/revisions"}],"predecessor-version":[{"id":487962,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/487959\/revisions\/487962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/487961"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=487959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=487959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=487959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}