{"id":587082,"date":"2026-07-04T08:20:27","date_gmt":"2026-07-04T11:20:27","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=587082"},"modified":"2026-07-04T10:37:25","modified_gmt":"2026-07-04T13:37:25","slug":"sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/","title":{"rendered":"S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda"},"content":{"rendered":"<p style=\"text-align: justify;\">Asunci\u00f3n, Agencia IP-.- Este s\u00e1bado se prev\u00e9 un ambiente fr\u00edo durante las primeras horas de la jornada y fresco por la tarde. Las temperaturas m\u00e1ximas oscilar\u00edan entre 13 y 21\u00b0C en gran parte del pa\u00eds. Adem\u00e1s, se espera cielo mayormente nublado y vientos predominantes del sector sureste.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Para ma\u00f1ana, domingo 05, persistir\u00eda un ambiente fr\u00edo a fresco e incluso c\u00e1lido en algunos sectores del territorio nacional.<\/p>\n<p style=\"text-align: justify;\">Las temperaturas m\u00ednimas oscilar\u00edan entre 8 y 13\u00b0C en ambas regiones del pa\u00eds, mientras que las m\u00e1ximas se ubicar\u00edan entre 15 y 20\u00b0C en el sur y centro de la regi\u00f3n Oriental y Occidental, y entre 21 y 23\u00b0C en el este y norte de ambas regiones.<\/p>\n<p style=\"text-align: justify;\">Para el lunes 06, se prev\u00e9 nuevamente un ambiente fresco en gran parte del territorio nacional.<\/p>\n<p style=\"text-align: justify;\">En cuanto a las precipitaciones, para hoy la probabilidad es muy baja. Sin embargo, al final de la jornada del domingo 05 se prev\u00e9n lluvias dispersas sobre el sur de la regi\u00f3n Oriental y el oeste de la regi\u00f3n Occidental, las cuales se extender\u00edan durante el lunes 06 a gran parte del territorio nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Agencia IP-.- Este s\u00e1bado se prev\u00e9 un ambiente fr\u00edo durante las primeras horas de la jornada y fresco por la tarde. Las temperaturas m\u00e1ximas oscilar\u00edan entre 13 y 21\u00b0C en gran parte del pa\u00eds. Adem\u00e1s, se espera cielo mayormente nublado y vientos predominantes del sector sureste.<\/p>\n","protected":false},"author":2,"featured_media":496844,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-587082","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Agencia IP-.- Este s\u00e1bado se prev\u00e9 un ambiente fr\u00edo durante las primeras horas de la jornada y fresco por la tarde. Las temperaturas m\u00e1ximas oscilar\u00edan entre 13 y 21\u00b0C en gran parte del pa\u00eds. Adem\u00e1s, se espera cielo mayormente nublado y vientos predominantes del sector sureste.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-04T11:20:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-04T13:37:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/04\/clima-nublado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"737\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roque Mereles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roque Mereles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/\"},\"author\":{\"name\":\"Roque Mereles\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/7ec1ca00d0a9301ecc37fff902ff6741\"},\"headline\":\"S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda\",\"datePublished\":\"2026-07-04T11:20:27+00:00\",\"dateModified\":\"2026-07-04T13:37:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/\"},\"wordCount\":213,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/clima-nublado.jpg\",\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/\",\"name\":\"S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/clima-nublado.jpg\",\"datePublished\":\"2026-07-04T11:20:27+00:00\",\"dateModified\":\"2026-07-04T13:37:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/clima-nublado.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/clima-nublado.jpg\",\"width\":1599,\"height\":737},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/04\\\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/7ec1ca00d0a9301ecc37fff902ff6741\",\"name\":\"Roque Mereles\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/rmereles\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/","og_locale":"es_ES","og_type":"article","og_title":"S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda - .::Agencia IP::.","og_description":"Asunci\u00f3n, Agencia IP-.- Este s\u00e1bado se prev\u00e9 un ambiente fr\u00edo durante las primeras horas de la jornada y fresco por la tarde. Las temperaturas m\u00e1ximas oscilar\u00edan entre 13 y 21\u00b0C en gran parte del pa\u00eds. Adem\u00e1s, se espera cielo mayormente nublado y vientos predominantes del sector sureste.","og_url":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2026-07-04T11:20:27+00:00","article_modified_time":"2026-07-04T13:37:25+00:00","og_image":[{"width":1599,"height":737,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/04\/clima-nublado.jpg","type":"image\/jpeg"}],"author":"Roque Mereles","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Roque Mereles","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/"},"author":{"name":"Roque Mereles","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/7ec1ca00d0a9301ecc37fff902ff6741"},"headline":"S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda","datePublished":"2026-07-04T11:20:27+00:00","dateModified":"2026-07-04T13:37:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/"},"wordCount":213,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/04\/clima-nublado.jpg","articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/","url":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/","name":"S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/04\/clima-nublado.jpg","datePublished":"2026-07-04T11:20:27+00:00","dateModified":"2026-07-04T13:37:25+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/04\/clima-nublado.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2024\/04\/clima-nublado.jpg","width":1599,"height":737},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/04\/sabado-con-cielo-nublado-y-fresco-a-lo-largo-del-dia-anuncia-meteorologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"S\u00e1bado con cielo nublado y fresco a lo largo del d\u00eda, anuncia Meteorolog\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/7ec1ca00d0a9301ecc37fff902ff6741","name":"Roque Mereles","url":"https:\/\/www.ip.gov.py\/ip\/author\/rmereles\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/587082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=587082"}],"version-history":[{"count":1,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/587082\/revisions"}],"predecessor-version":[{"id":587083,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/587082\/revisions\/587083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/496844"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=587082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=587082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=587082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}