{"id":587696,"date":"2026-07-09T10:17:36","date_gmt":"2026-07-09T13:17:36","guid":{"rendered":"https:\/\/www.ip.gov.py\/ip\/?p=587696"},"modified":"2026-07-09T10:18:05","modified_gmt":"2026-07-09T13:18:05","slug":"el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/","title":{"rendered":"\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Asunci\u00f3n, Agencia IP.<\/strong><\/em>La Secretar\u00eda Nacional de Cultura (SNC) invita a participar este viernes 10 y s\u00e1bado 11 de julio de una variada agenda cultural en el Centro Hist\u00f3rico de Asunci\u00f3n, con m\u00fasica paraguaya, folklore fusi\u00f3n, ferias, muestras y actividades abiertas al p\u00fablico.<!--more--><\/p>\n<p style=\"text-align: justify;\">La programaci\u00f3n inicia el viernes 10, a las 19:00, con una nueva edici\u00f3n de <strong>\u201cEl Puerto Suena\u201d<\/strong> en el Centro Cultural del Puerto de Asunci\u00f3n, donde la Orquesta Nacional de M\u00fasica Popular (ONAMP), bajo la direcci\u00f3n del maestro Luis \u00c1lvarez, presentar\u00e1 un homenaje a Mauricio Cardozo Ocampo. El repertorio incluir\u00e1 reconocidas obras como Galopera, Paraguaya linda, Polca Mar\u00eda y Fantas\u00eda paraguaya. El acceso ser\u00e1 libre y gratuito, hasta completar aforo.<\/p>\n<p style=\"text-align: justify;\">El s\u00e1bado 11, de 15:00 a 23:00, se desarrollar\u00e1 una nueva edici\u00f3n de<strong> \u201cEmbarcate\u201d, con la Fiesta del Fuego<\/strong>, encuentro de folklore fusi\u00f3n que reunir\u00e1 a artistas como Bohemia Urbana, Joaju Cuarteto, Ricardo Flecha, Kamba Kua y otros referentes, adem\u00e1s de una feria con gastronom\u00eda, artesan\u00eda, emprendimientos y actividades para el p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">Como parte de la Feria Palmear, tambi\u00e9n se realizar\u00e1 una edici\u00f3n especial de San Juan en calle Palma, de 11:00 a 23:00, con comidas t\u00edpicas, juegos tradicionales y m\u00fasica.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, el Archivo Nacional de Asunci\u00f3n habilita la muestra documental \u201c4 tiempos de la Rep\u00fablica. Las constituciones del Paraguay\u201d, con un recorrido por las Constituciones de 1870, 1940, 1967 y 1992, mientras que otros espacios culturales ofrecer\u00e1n exposiciones y actividades, entre ellas la muestra \u201cELBA\u201d del fot\u00f3grafo paraguayo Ra\u00fal Villalba en el Museo Nacional de Bellas Artes y un concierto de m\u00fasica de c\u00e1mara del Mangor\u00e9 Quartet en el Espacio Cultural Staudt.<\/p>\n<p style=\"text-align: justify;\">La SNC se\u00f1al\u00f3 que estas actividades forman parte de las acciones para dinamizar los espacios culturales y acercar propuestas art\u00edsticas gratuitas a la ciudadan\u00eda en el Centro Hist\u00f3rico de Asunci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, Agencia IP.La Secretar\u00eda Nacional de Cultura (SNC) invita a participar este viernes 10 y s\u00e1bado 11 de julio de una variada agenda cultural en el Centro Hist\u00f3rico de Asunci\u00f3n, con m\u00fasica paraguaya, folklore fusi\u00f3n, ferias, muestras y actividades abiertas al p\u00fablico.<\/p>\n","protected":false},"author":48,"featured_media":587707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-587696","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, Agencia IP.La Secretar\u00eda Nacional de Cultura (SNC) invita a participar este viernes 10 y s\u00e1bado 11 de julio de una variada agenda cultural en el Centro Hist\u00f3rico de Asunci\u00f3n, con m\u00fasica paraguaya, folklore fusi\u00f3n, ferias, muestras y actividades abiertas al p\u00fablico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-09T13:17:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T13:18:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2026\/07\/Copia-de-54605491460_7507d5f302_o-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pamela Elizabeth Vargas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pamela Elizabeth Vargas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/\"},\"author\":{\"name\":\"Pamela Elizabeth Vargas\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/076ae5920afed658ff2785ebe6f903d1\"},\"headline\":\"\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n\",\"datePublished\":\"2026-07-09T13:17:36+00:00\",\"dateModified\":\"2026-07-09T13:18:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/\"},\"wordCount\":341,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Copia-de-54605491460_7507d5f302_o-scaled.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/\",\"name\":\"\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Copia-de-54605491460_7507d5f302_o-scaled.jpg\",\"datePublished\":\"2026-07-09T13:17:36+00:00\",\"dateModified\":\"2026-07-09T13:18:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Copia-de-54605491460_7507d5f302_o-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Copia-de-54605491460_7507d5f302_o-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2026\\\/07\\\/09\\\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/076ae5920afed658ff2785ebe6f903d1\",\"name\":\"Pamela Elizabeth Vargas\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/pvargas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n - .::Agencia IP::.","og_description":"Asunci\u00f3n, Agencia IP.La Secretar\u00eda Nacional de Cultura (SNC) invita a participar este viernes 10 y s\u00e1bado 11 de julio de una variada agenda cultural en el Centro Hist\u00f3rico de Asunci\u00f3n, con m\u00fasica paraguaya, folklore fusi\u00f3n, ferias, muestras y actividades abiertas al p\u00fablico.","og_url":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2026-07-09T13:17:36+00:00","article_modified_time":"2026-07-09T13:18:05+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2026\/07\/Copia-de-54605491460_7507d5f302_o-scaled.jpg","type":"image\/jpeg"}],"author":"Pamela Elizabeth Vargas","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Pamela Elizabeth Vargas","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/"},"author":{"name":"Pamela Elizabeth Vargas","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/076ae5920afed658ff2785ebe6f903d1"},"headline":"\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n","datePublished":"2026-07-09T13:17:36+00:00","dateModified":"2026-07-09T13:18:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/"},"wordCount":341,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2026\/07\/Copia-de-54605491460_7507d5f302_o-scaled.jpg","articleSection":["Cultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/","url":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/","name":"\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2026\/07\/Copia-de-54605491460_7507d5f302_o-scaled.jpg","datePublished":"2026-07-09T13:17:36+00:00","dateModified":"2026-07-09T13:18:05+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2026\/07\/Copia-de-54605491460_7507d5f302_o-scaled.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2026\/07\/Copia-de-54605491460_7507d5f302_o-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2026\/07\/09\/el-puerto-suena-y-fiesta-del-fuego-entre-las-principales-propuestas-para-disfrutar-el-fin-de-semana-en-asuncion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"\u201cEl Puerto Suena\u201d y \u201cFiesta del Fuego\u201d entre las principales propuestas para disfrutar el fin de semana en Asunci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/076ae5920afed658ff2785ebe6f903d1","name":"Pamela Elizabeth Vargas","url":"https:\/\/www.ip.gov.py\/ip\/author\/pvargas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/587696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=587696"}],"version-history":[{"count":2,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/587696\/revisions"}],"predecessor-version":[{"id":587709,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/587696\/revisions\/587709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/587707"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=587696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=587696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=587696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}