{"id":668,"date":"2015-01-31T14:39:52","date_gmt":"2015-01-31T14:39:52","guid":{"rendered":"http:\/\/desarrollo.ip.gov.py\/ip\/?p=668"},"modified":"2015-01-31T14:39:52","modified_gmt":"2015-01-31T14:39:52","slug":"consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/","title":{"rendered":"Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>Asunci\u00f3n, IP.-<\/em> A fin de que la ciudadan\u00eda conozca a los postulantes al cargo de Ministro de la Corte Suprema de Justicia, el Consejo de la Magistratura public\u00f3 en su <a href=\"http:\/\/www.consejodelamagistratura.gov.py\">p\u00e1gina web<\/a> los perfiles de 51 doctores y doctoras en derecho.<!--more-->La disponibilidad del perfil de los candidatos contribuir\u00e1 tambi\u00e9n para que, en el plazo establecido del 31 de enero al 09 de febrero del corriente, se puedan acercar las pruebas que afecte la notoria honorabilidad de los mismos.<\/p>\n<p style=\"text-align: justify;\">Esta denuncia se puede realizar a trav\u00e9s de la ventana habilitada en la p\u00e1gina web y la misma es de car\u00e1cter confidencial corri\u00e9ndose traslado al postulante afectado que podr\u00e1 realizar su descargo en las Audiencias P\u00fablicas.<\/p>\n<p style=\"text-align: justify;\">Igualmente se pueden realizar personalmente a la Secretar\u00eda General en Avda. Mcal. L\u00f3pez 410 esq.\/ Pa\u00ed P\u00e9rez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asunci\u00f3n, IP.- A fin de que la ciudadan\u00eda conozca a los postulantes al cargo de Ministro de la Corte Suprema de Justicia, el Consejo de la Magistratura public\u00f3 en su p\u00e1gina web los perfiles de 51 doctores y doctoras en derecho.<\/p>\n","protected":false},"author":2,"featured_media":670,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-668","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Asunci\u00f3n, IP.- A fin de que la ciudadan\u00eda conozca a los postulantes al cargo de Ministro de la Corte Suprema de Justicia, el Consejo de la Magistratura public\u00f3 en su p\u00e1gina web los perfiles de 51 doctores y doctoras en derecho.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-31T14:39:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/01\/palacio-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"484\" \/>\n\t<meta property=\"og:image:height\" content=\"322\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roque Mereles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roque Mereles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/\"},\"author\":{\"name\":\"Roque Mereles\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/7ec1ca00d0a9301ecc37fff902ff6741\"},\"headline\":\"Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte\",\"datePublished\":\"2015-01-31T14:39:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/\"},\"wordCount\":152,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/palacio-2.jpg\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/\",\"name\":\"Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/palacio-2.jpg\",\"datePublished\":\"2015-01-31T14:39:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/palacio-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/palacio-2.jpg\",\"width\":484,\"height\":322},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/01\\\/31\\\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/7ec1ca00d0a9301ecc37fff902ff6741\",\"name\":\"Roque Mereles\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/rmereles\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/","og_locale":"es_ES","og_type":"article","og_title":"Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte - .::Agencia IP::.","og_description":"Asunci\u00f3n, IP.- A fin de que la ciudadan\u00eda conozca a los postulantes al cargo de Ministro de la Corte Suprema de Justicia, el Consejo de la Magistratura public\u00f3 en su p\u00e1gina web los perfiles de 51 doctores y doctoras en derecho.","og_url":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2015-01-31T14:39:52+00:00","og_image":[{"width":484,"height":322,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/01\/palacio-2.jpg","type":"image\/jpeg"}],"author":"Roque Mereles","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"Roque Mereles","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/"},"author":{"name":"Roque Mereles","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/7ec1ca00d0a9301ecc37fff902ff6741"},"headline":"Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte","datePublished":"2015-01-31T14:39:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/"},"wordCount":152,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/01\/palacio-2.jpg","articleSection":["Pol\u00edtica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/","url":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/","name":"Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/01\/palacio-2.jpg","datePublished":"2015-01-31T14:39:52+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/01\/palacio-2.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/01\/palacio-2.jpg","width":484,"height":322},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2015\/01\/31\/consejo-de-la-magistratura-publico-perfil-de-51-postulantes-a-la-corte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Consejo de la Magistratura public\u00f3 perfil de 51 postulantes a la Corte"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/7ec1ca00d0a9301ecc37fff902ff6741","name":"Roque Mereles","url":"https:\/\/www.ip.gov.py\/ip\/author\/rmereles\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=668"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/670"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}