{"id":8253,"date":"2015-03-16T10:03:30","date_gmt":"2015-03-16T10:03:30","guid":{"rendered":"http:\/\/desarrollo.ip.gov.py\/ip\/?p=8253"},"modified":"2015-03-16T10:03:30","modified_gmt":"2015-03-16T10:03:30","slug":"tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil","status":"publish","type":"post","link":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/","title":{"rendered":"Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Sao Paulo.-<\/strong><\/em> Tras las protestas que llevaron a lascalles a m\u00e1s de un mill\u00f3n de manifestantes en todo Brasil, elgobierno de la presidenta Dilma Rousseff anunci\u00f3 anoche quepresentar\u00e1 en breve un paquete de medidas para combatir lacorrupci\u00f3n y la impunidad.<!--more--><\/p>\n<p style=\"text-align: justify;\">\u201cBrasil est\u00e1 lejos del golpismo. El gobierno est\u00e1 atento y se muestra dispuesto como siempre a escuchar la voz de la calle\u201d<\/p>\n<p style=\"text-align: justify;\">\u201cBrasil est\u00e1 lejos del golpismo. El gobierno est\u00e1 atento y se muestra dispuesto como siempre a escuchar la voz de la calle\u201d, dijo el ministro de Justicia, Jos\u00e9 Eduardo Cardozo. Seg\u00fan el funcionario, quien durante la tarde fue convocado por la mandataria al palacio de la Alvorada, las protestas de hoy muestran \u201cel deseo de todos los brasile\u00f1os de combatir lacorrupci\u00f3n y la impunidad\u201d.<\/p>\n<p style=\"text-align: justify;\">Cardozo dijo que tambi\u00e9n el gobierno est\u00e1 comprometido en tal prop\u00f3sito y anunciar\u00e1 en breve un conjunto de medidas contra la corrupci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La propuesta ser\u00e1 enviada al Parlamento antes de los seis meses prometidos por Rousseff en campa\u00f1a electoral, asegur\u00f3 elministro. \u201cSon cuestiones que deben ser acordadas entre los distintospoderes\u201d, precis\u00f3 Cardozo.<\/p>\n<p style=\"text-align: justify;\">Cerca de un mill\u00f3n y medio de brasile\u00f1os protestaron ayer pac\u00edficamente en todo el pa\u00eds contra la presidenta Dilma Rousseff, que enfrenta un complejo c\u00f3ctel de tensi\u00f3n social, pol\u00edtica y econ\u00f3mica derivada en parte del gran esc\u00e1ndalo de corrupci\u00f3n en Petrobras. La gobernante se encuentra en su peor momento pol\u00edtico, ya que algunos exigen directamente su destituci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La mayor protesta tuvo lugar en S\u00e3o Paulo, que convoc\u00f3 a un mill\u00f3n de personas, seg\u00fan la polic\u00eda, vestidas en su mayor\u00eda con la camiseta amarilla y verde de la selecci\u00f3n brasile\u00f1a. Las manifestaciones congregaron a otro medio mill\u00f3n de personas en unas 83 ciudades, en protestas que igualaron el tama\u00f1o de las celebradas en junio de 2013, cuando los brasile\u00f1os salieron espont\u00e1neamente a las calles para pedir el fin de la corrupci\u00f3n y m\u00e1s gastos en transporte, salud y educaci\u00f3n, en vez de en la Copa del Mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sao Paulo.- Tras las protestas que llevaron a lascalles a m\u00e1s de un mill\u00f3n de manifestantes en todo Brasil, elgobierno de la presidenta Dilma Rousseff anunci\u00f3 anoche quepresentar\u00e1 en breve un paquete de medidas para combatir lacorrupci\u00f3n y la impunidad.<\/p>\n","protected":false},"author":11,"featured_media":8254,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-8253","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil - .::Agencia IP::.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil - .::Agencia IP::.\" \/>\n<meta property=\"og:description\" content=\"Sao Paulo.- Tras las protestas que llevaron a lascalles a m\u00e1s de un mill\u00f3n de manifestantes en todo Brasil, elgobierno de la presidenta Dilma Rousseff anunci\u00f3 anoche quepresentar\u00e1 en breve un paquete de medidas para combatir lacorrupci\u00f3n y la impunidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\".::Agencia IP::.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPParaguay\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-16T10:03:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/03\/brasiu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vrios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:site\" content=\"@IPParaguay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vrios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/\"},\"author\":{\"name\":\"vrios\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/fa3668852e893cb0423795330f919039\"},\"headline\":\"Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil\",\"datePublished\":\"2015-03-16T10:03:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/\"},\"wordCount\":368,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/brasiu.jpg\",\"articleSection\":[\"Internacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/\",\"name\":\"Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil - .::Agencia IP::.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/brasiu.jpg\",\"datePublished\":\"2015-03-16T10:03:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/brasiu.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/brasiu.jpg\",\"width\":600,\"height\":338,\"caption\":\"actualidad.rt.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/2015\\\/03\\\/16\\\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#website\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"name\":\".::Agencia IP::.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#organization\",\"name\":\"Agencia IP\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/LOGO-ip-mobile.png\",\"width\":140,\"height\":44,\"caption\":\"Agencia IP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPParaguay\\\/\",\"https:\\\/\\\/x.com\\\/IPParaguay\",\"https:\\\/\\\/www.instagram.com\\\/IPParaguay\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/#\\\/schema\\\/person\\\/fa3668852e893cb0423795330f919039\",\"name\":\"vrios\",\"url\":\"https:\\\/\\\/www.ip.gov.py\\\/ip\\\/author\\\/vrios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil - .::Agencia IP::.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/","og_locale":"es_ES","og_type":"article","og_title":"Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil - .::Agencia IP::.","og_description":"Sao Paulo.- Tras las protestas que llevaron a lascalles a m\u00e1s de un mill\u00f3n de manifestantes en todo Brasil, elgobierno de la presidenta Dilma Rousseff anunci\u00f3 anoche quepresentar\u00e1 en breve un paquete de medidas para combatir lacorrupci\u00f3n y la impunidad.","og_url":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/","og_site_name":".::Agencia IP::.","article_publisher":"https:\/\/www.facebook.com\/IPParaguay\/","article_published_time":"2015-03-16T10:03:30+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/03\/brasiu.jpg","type":"image\/jpeg"}],"author":"vrios","twitter_card":"summary_large_image","twitter_creator":"@IPParaguay","twitter_site":"@IPParaguay","twitter_misc":{"Escrito por":"vrios","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/#article","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/"},"author":{"name":"vrios","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/fa3668852e893cb0423795330f919039"},"headline":"Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil","datePublished":"2015-03-16T10:03:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/"},"wordCount":368,"publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/03\/brasiu.jpg","articleSection":["Internacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/","url":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/","name":"Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil - .::Agencia IP::.","isPartOf":{"@id":"https:\/\/www.ip.gov.py\/ip\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/#primaryimage"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/03\/brasiu.jpg","datePublished":"2015-03-16T10:03:30+00:00","breadcrumb":{"@id":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/#primaryimage","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/03\/brasiu.jpg","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2015\/03\/brasiu.jpg","width":600,"height":338,"caption":"actualidad.rt.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ip.gov.py\/ip\/2015\/03\/16\/tras-protesta-gobierno-anuncia-medida-anticorrupcion-en-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ip.gov.py\/ip\/"},{"@type":"ListItem","position":2,"name":"Tras protesta, gobierno anuncia medida anticorrupci\u00f3n en Brasil"}]},{"@type":"WebSite","@id":"https:\/\/www.ip.gov.py\/ip\/#website","url":"https:\/\/www.ip.gov.py\/ip\/","name":".::Agencia IP::.","description":"","publisher":{"@id":"https:\/\/www.ip.gov.py\/ip\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ip.gov.py\/ip\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ip.gov.py\/ip\/#organization","name":"Agencia IP","url":"https:\/\/www.ip.gov.py\/ip\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/","url":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","contentUrl":"https:\/\/www.ip.gov.py\/ip\/wp-content\/uploads\/2019\/03\/LOGO-ip-mobile.png","width":140,"height":44,"caption":"Agencia IP"},"image":{"@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPParaguay\/","https:\/\/x.com\/IPParaguay","https:\/\/www.instagram.com\/IPParaguay"]},{"@type":"Person","@id":"https:\/\/www.ip.gov.py\/ip\/#\/schema\/person\/fa3668852e893cb0423795330f919039","name":"vrios","url":"https:\/\/www.ip.gov.py\/ip\/author\/vrios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/8253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/comments?post=8253"}],"version-history":[{"count":0,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/posts\/8253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media\/8254"}],"wp:attachment":[{"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/media?parent=8253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/categories?post=8253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ip.gov.py\/ip\/wp-json\/wp\/v2\/tags?post=8253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}